{"id":108215,"date":"2012-08-17T00:02:46","date_gmt":"2012-08-17T04:32:46","guid":{"rendered":"http:\/\/www.moonmentum.com\/blog\/?p=108215"},"modified":"2012-08-17T02:32:56","modified_gmt":"2012-08-17T07:02:56","slug":"convierte-al-universo-en-tu-aliado","status":"publish","type":"post","link":"https:\/\/moonmentum.com\/blog\/pronostico\/clima-astrologico\/convierte-al-universo-en-tu-aliado\/","title":{"rendered":"Convierte al Universo en tu aliado"},"content":{"rendered":"<p><a rel=\"attachment wp-att-108570\" href=\"http:\/\/www.moonmentum.com\/blog\/pronostico\/index\/convierte-al-universo-en-tu-aliado\/attachment\/clima-15\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-108570 lazyload\" style=\"--smush-placeholder-width: 250px; --smush-placeholder-aspect-ratio: 250\/197;float: left; margin: 6px; border: 0px;\" title=\"clima\" data-src=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2012\/08\/3243facc4f85d641399c632e11eec149-300x236.jpg\" alt=\"clima\" width=\"250\" height=\"197\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><noscript><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-108570\" style=\"float: left; margin: 6px; border: 0px;\" title=\"clima\" src=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2012\/08\/3243facc4f85d641399c632e11eec149-300x236.jpg\" alt=\"clima\" width=\"250\" height=\"197\" \/><\/noscript><\/a>Hay tanta energ\u00eda en el Universo<span style=\"color: #888888;\"> <em>(Cuadratura \u201cT\u201d, Luna Nueva , encuentro de Marte y Saturno)<\/em><\/span> que produce campos electromagn\u00e9ticos que pueden afectar ondas y frecuencia presentes en la atm\u00f3sfera, mi consejo es realizar actividades que envuelvan el colectivo bien sea energ\u00e9tico, ecol\u00f3gico o comunitario (en funci\u00f3n de las masas) al hacerlo el Universo se convertir\u00e1 o en tu aliado o en tu c\u00f3mplice dependiendo del nivel de protagonismo que logres.<\/p>\n<p><strong> <\/strong><\/p>\n<p><strong>La cuadratura T:<\/strong> En s\u00ed misma no es una figura \u201cmala\u201d sino que indica un fuerte consumo de energ\u00eda sujeta a ataduras con los dem\u00e1s, a nivel colectivo se trata de ataduras sociales, pol\u00edticas y culturales, a nivel individual induce a la liberaci\u00f3n de esas ataduras, a nivel humano activa nuevos experimentos en la clonaci\u00f3n de alimentos y entes vivos, a\u00a0nivel ambiental \u00a0genera activaci\u00f3n de fen\u00f3menos naturales.<!--more--><\/p>\n<p><strong>Activaci\u00f3n del Karma a nivel personal y colectivo.<\/strong><\/p>\n<blockquote><p><strong>Karma.<\/strong> En algunas religiones de la India, energ\u00eda derivada de los actos que condiciona cada una de las sucesivas reencarnaciones, hasta que se alcanza la perfecci\u00f3n. || En otras creencias, fuerza espiritual.<br \/>\nFuente: Microsoft\u00ae Encarta\u00ae 2006.<strong> <\/strong><\/p><\/blockquote>\n<p>Estamos frente a una energ\u00eda que nos \u201cmide\u201d\u2026 momento de ejecutar con extrema precauci\u00f3n\u2026El mundo es impulsado por los movimientos de los colosos en el cielo,\u00a0todos con su cuota\u00a0y sus l\u00edmites de poder.<\/p>\n<p>Pero hay algunos que en momentos se apropian de la b\u00f3veda celeste en encuentros de proporci\u00f3n \u00e9pica, trasmitiendo a la humanidad a trav\u00e9s de sus ondas una percepci\u00f3n, as\u00ed sea inconsciente, de la magnitud de su encuentro.<\/p>\n<p><strong> \u00bfC\u00f3mo te afectar\u00e1 a nivel personal?<\/strong><strong> <\/strong><\/p>\n<p>Un encuentro como este normalmente se maneja a nivel de esferas superiores de poder: las logias, las sociedades herm\u00e9ticas, los gobiernos\u2026 debes estar muy atento a los mensajes que recibes en el trabajo, los medios y tus sociedades y as\u00ed evitar cualquier intento de un manejo de poder a nivel energ\u00e9tico.<\/p>\n<p>A nivel personal puedes sentir una ansiedad que no sabes definir, un presagio de eventos fuera de tu control, trabaja a nivel de masas para aprovechar el poder y as\u00ed vibrar a la misma frecuencia de las energ\u00edas, puede ser organizando a tu comunidad o creando un movimiento de protecci\u00f3n ambiental, lo importante es tomar protagonismo sobre las energ\u00edas del d\u00eda.<\/p>\n<ul>\n<li>Organiza grupos grandes de gente para un fin com\u00fan: puede ser social, ecol\u00f3gico o energ\u00e9tico.<\/li>\n<li>Mantente atento a todos los mensajes que escuches, evita la manipulaci\u00f3n.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Hay tanta energ\u00eda en el Universo (Cuadratura \u201cT\u201d, Luna Nueva , encuentro de Marte y Saturno) que produce campos electromagn\u00e9ticos que pueden afectar ondas y frecuencia presentes en la atm\u00f3sfera&#8230; <a href=\"http:\/\/www.moonmentum.com\/blog\/pronostico\/index\/convierte-al-universo-en-tu-aliado\/\"> Ver m\u00e1s&#8230;<\/a><\/p>\n","protected":false},"author":3,"featured_media":108570,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[314,3585],"class_list":{"0":"post-108215","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-clima-astrologico","8":"tag-karma","9":"tag-la-cuadratura-t"},"_links":{"self":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts\/108215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/comments?post=108215"}],"version-history":[{"count":0,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts\/108215\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/media\/108570"}],"wp:attachment":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/media?parent=108215"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/categories?post=108215"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/tags?post=108215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}