{"id":110910,"date":"2012-09-07T00:02:10","date_gmt":"2012-09-07T04:32:10","guid":{"rendered":"http:\/\/www.moonmentum.com\/blog\/?p=110910"},"modified":"2013-07-11T10:26:44","modified_gmt":"2013-07-11T14:56:44","slug":"mensajes-que-trascienden-en-el-tiempo","status":"publish","type":"post","link":"https:\/\/moonmentum.com\/blog\/pronostico\/clima-astrologico\/mensajes-que-trascienden-en-el-tiempo\/","title":{"rendered":"Mensajes que trascienden en el tiempo"},"content":{"rendered":"<p><a href=\"http:\/\/www.moonmentum.com\/blog\/pronostico\/index\/mensajes-que-trascienden-en-el-tiempo\/attachment\/carpe-diem-1\/\" rel=\"attachment wp-att-111439\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-111439 lazyload\" style=\"--smush-placeholder-width: 250px; --smush-placeholder-aspect-ratio: 250\/178;float: left; margin: 6px; border: 0px;\" title=\"carpe-diem-1\" alt=\"\" data-src=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2012\/09\/0457a3c528a2de32fc48c993b21fe831-300x213.jpg\" width=\"250\" height=\"178\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><noscript><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-111439\" style=\"float: left; margin: 6px; border: 0px;\" title=\"carpe-diem-1\" alt=\"\" src=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2012\/09\/0457a3c528a2de32fc48c993b21fe831-300x213.jpg\" width=\"250\" height=\"178\" \/><\/noscript><\/a>No permitas que el tiempo se te escape. Este es un d\u00eda lleno de un mensaje, cu\u00e1nticamente significativo en la vida de cada uno de nosotros, por ello espero que mi voz se haga <a href=\" http:\/\/www.moonmentum.com\/blog\/category\/efemerides\/semilla-del-dia\/\" target=\"_blank\">eco<\/a> y muchos comprendamos el significado de la palabra\u00a0<strong>\u201cTempo\u201d<\/strong>.<\/p>\n<blockquote><p><em>Seg\u00fan Wikipedia: En terminolog\u00eda musical, tempo, movimiento o aire es la velocidad con que debe ejecutarse una pieza de m\u00fasica.<\/em><\/p><\/blockquote>\n<p>Ayer es historia. Ma\u00f1ana es misterio. Hoy es un regalo, por eso es que se llama\u00a0<strong>\u00a1Presente!<\/strong> de ah\u00ed nace mi insistencia con que tengan \u201cPresencia\u201d porque el tiempo no espera a nadie.<\/p>\n<p>La realidad es lo que haces con ella, cada d\u00eda te despiertas en la ma\u00f1ana y tomas las riendas de formas diferentes.<\/p>\n<p>En la manera que pasan los d\u00edas, nuestra posici\u00f3n y forma de jugar el \u201cjuego de la vida\u201d se va afianzando, limitando la capacidad de cambio hasta constituir una rigidez que limita nuestra visi\u00f3n.<!--more--><\/p>\n<p>Si recuerdas que esa posici\u00f3n no es m\u00e1s que tu propia decisi\u00f3n, puedes avanzar de forma segura hacia una transici\u00f3n de vida, la cual obedecer\u00e1 a la fortaleza de tu propia raz\u00f3n por encima de tu costumbre, descubriendo que eres tan s\u00f3lo t\u00fa qui\u00e9n marca las acciones de tu d\u00eda.<\/p>\n<p>Hoy, al despertar, recuerda que eres libre y al hacerlo has transici\u00f3n a ese estado de fluidez en la cual te puedes adaptar a las realidades del Universo como t\u00fa quieras, buscando el camino que te lleve a la <a href=\"http:\/\/www.moonmentum.com\/blog\/category\/pronostico\/afirmacion-del-dia\/\" target=\"_blank\">plenitud<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No permitas que el tiempo se te escape. Este es un d\u00eda lleno de un mensaje, cu\u00e1nticamente significativo en la vida de cada uno de nosotros&#8230; <a href=\"http:\/\/www.moonmentum.com\/blog\/pronostico\/index\/mensajes-que-trascienden-en-el-tiempo\/\"> Ver m\u00e1s&#8230;<\/a><\/p>\n","protected":false},"author":3,"featured_media":111439,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[6420,4655,8906,9053,8318,515],"class_list":{"0":"post-110910","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-clima-astrologico","8":"tag-eco","9":"tag-mensaje","10":"tag-plenitud","11":"tag-tempo","12":"tag-temporada-de-libra","13":"tag-tiempo"},"_links":{"self":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts\/110910","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/comments?post=110910"}],"version-history":[{"count":0,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts\/110910\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/media\/111439"}],"wp:attachment":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/media?parent=110910"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/categories?post=110910"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/tags?post=110910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}