	<style type="text/css">
		.postTabs_divs{
	padding: 4px;	
}


.postTabs_titles{
	display:none;	
}

ul.postTabs
	{
	margin:0px 0px 1em !important;
	padding: 0.2em 1em 0.2em 20px !important;
	border-bottom: 1px solid #ccc !important;
	font-size: 14px;
	list-style-type: none !important;
	line-height:normal;
	text-align: left;
	display: block !important;
	background: none;
	}

ul.postTabs li
	{	
	display: inline !important;
	font-size: 14px;
	line-height:normal;
	background: none;
	padding: 0px;
	margin: 0px;
	}
  
ul.postTabs li:before{
content: none;	
}  
  	
ul.postTabs li a
	{
	text-decoration: none;
	background: #808080;
	border: 1px solid #ccc  !important;
	padding: 0.2em 0.4em !important;
	color: #ffffff !important;
	outline:none;	
	cursor: pointer;
	
	}
	
ul.postTabs li.postTabs_curr a{
	border-bottom: 1px solid #fff  !important;
	background: #fff;
	color: #000000 !important;
	text-decoration: none;
	
	}

ul.postTabs li a:hover
	{
	color: #666 !important;
	background: #d4d4d4;
	text-decoration: none;
	
	}

.postTabsNavigation{
	display: block !important;
	overflow:hidden;
}

.postTabs_nav_next{
	float:right;
}

.postTabs_nav_prev{
	float:left;
}

@media screen and (max-width: 699px) {
	ul.postTabs li {
		display: block !important;
		width: 100%;
		margin: -3px;
	}
	ul.postTabs li a {
		display: block;
		width: 96%;
	}
}	</style>
	{"id":113667,"date":"2012-09-24T01:39:07","date_gmt":"2012-09-24T06:09:07","guid":{"rendered":"http:\/\/www.moonmentum.com\/blog\/?p=113667"},"modified":"2012-09-24T01:58:18","modified_gmt":"2012-09-24T06:28:18","slug":"philippus-aureolus-theophrastus-bombastus-von-hohenheim-paracelso","status":"publish","type":"post","link":"https:\/\/moonmentum.com\/blog\/archivo\/multimedia\/philippus-aureolus-theophrastus-bombastus-von-hohenheim-paracelso\/","title":{"rendered":"Philippus Aureolus Theophrastus Bombastus von Hohenheim \u00abParacelso\u00bb"},"content":{"rendered":"<p><a href=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2012\/09\/7a48d01fc062231f4194faf9d812724e.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-113696 lazyload\" style=\"--smush-placeholder-width: 202px; --smush-placeholder-aspect-ratio: 202\/250;margin: 6px;\" title=\"Paracelso\" data-src=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2012\/09\/7a48d01fc062231f4194faf9d812724e.jpg\" alt=\"Paracelso\" width=\"202\" height=\"250\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><noscript><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-113696\" style=\"margin: 6px;\" title=\"Paracelso\" src=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2012\/09\/7a48d01fc062231f4194faf9d812724e.jpg\" alt=\"Paracelso\" width=\"202\" height=\"250\" \/><\/noscript><\/a>Philippus Aureolus Theophrastus Bombastus von Hohenheim (1493-1541). Aunque prefer\u00eda que lo llamaran Paracelso, fue un alquimista, m\u00e9dico y astr\u00f3logo suizo.<\/p>\n<p>Paracelso era un hombre cuya presencia deb\u00eda resultar inc\u00f3moda. De naturaleza desconfiada y curiosa, lo cuestiona todo, si no era visto por el mismo, era desconfiado, curioso y ten\u00eda esa arrogancia que generalmente acompa\u00f1a a la genialidad.<\/p>\n<p>Naci\u00f3 sobre Diciembre de 1493 en Suiza, hijo de Wilhelm von Hohenheim m\u00e9dico y qu\u00edmico acomodado y de la directora del hospital local. Recibi\u00f3 la educaci\u00f3n temprana de su padre, el futuro m\u00e9dico se acostumbr\u00f3 a o\u00edr hablar de los fundamentos de la qu\u00edmica, que luego aplicar\u00eda en su desarrollo profesional. Con 14 a\u00f1os, el joven Teofrasto se uni\u00f3 a los j\u00f3venes que iban de ciudad en ciudad buscando una universidad que saciara su ansia de conocimiento.<\/p>\n<p>Basilea, Tubinga, Viena, Colonia entre otras. Muchas ciudades vieron pasar al inquieto Paracelso, buscando los secretos de la medicina. Pero ni los tratados de Avicena o el gran m\u00e9dico \u00e1rabe, ni la sabidur\u00eda proveniente de Galeno saciaron la sed de conocimientos del joven Suizo.<!--more--><\/p>\n<p>Ya los 16 a\u00f1os estaba en a la Universidad de Basilea, pero pronto la abandon\u00f3 por el estudio de la qu\u00edmica y la alquimia con Withemina, Obispo de W\u00fcrzburg.\u00a0Trascendente\u00a0pues quienes estudiaban qu\u00edmica, medicina y alquimia en la\u00a0\u00e9poca\u00a0fueron los precursores de la moderna farmacolog\u00eda.<\/p>\n<p><a href=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2012\/09\/portada_obra_paracelso_siglo_xvi_custodiada_biblioteca_nacional_austria.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-113695 lazyload\" style=\"--smush-placeholder-width: 167px; --smush-placeholder-aspect-ratio: 167\/250;margin: 6px;\" title=\"Paracelso\" data-src=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2012\/09\/Portada_obra_Paracelso_siglo_XVI_custodiada_Biblioteca_Nacional_Austria-200x300.jpg\" alt=\"Paracelso\" width=\"167\" height=\"250\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><noscript><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-113695\" style=\"margin: 6px;\" title=\"Paracelso\" src=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2012\/09\/Portada_obra_Paracelso_siglo_XVI_custodiada_Biblioteca_Nacional_Austria-200x300.jpg\" alt=\"Paracelso\" width=\"167\" height=\"250\" \/><\/noscript><\/a>Viaj\u00f3 mucho, sosteni\u00e9ndose por la pr\u00e1ctica irregular de la medicina y la recolecci\u00f3n de una gran cantidad de conocimientos diversos, especialmente de la medicina popular, a trav\u00e9s de la asociaci\u00f3n con los barberos, los gitanos, y los verdugos, quienes eran en la \u00e9poca los encargados de curar y atender a los enfermos y heridos del pueblo.<\/p>\n<p>Paracelso se dio cuenta que entre los atanores de los alquimistas, en las consultas de los brujos, y en los hechizos de las brujas, se encontraban a veces secretos curativos que los m\u00e9dicos del status quo ni conoc\u00edan, ni conocer\u00edan nunca por sus anteojeras ideol\u00f3gicas.<\/p>\n<p>Se desempe\u00f1\u00f3 alg\u00fan tiempo como cirujano militar en los Pa\u00edses Bajos, Dinamarca e Italia, y aprendi\u00f3 la metalurgia pr\u00e1ctica en las minas en Tirol pertenecientes a la familia Fugger, que eran reconocidaos por su patrocinio del arte y la ciencia. Estudi\u00f3 con diligencia investigando los procesos de preparaci\u00f3n de metales e hizo experimentos en cuanto a sus virtudes medicinales. Sus curaciones, real o fingida, se expres\u00f3 en el extranjero, y fue llamado para prescribir a muchos de los grandes hombres de su \u00e9poca. Erasmo fue uno de sus pacientes.<\/p>\n<p>Por recomendaci\u00f3n de Ecolampadio, en 1526, fue nombrado profesor de f\u00edsica y la cirug\u00eda en Basilea, inaugur\u00f3 su carrera como profesor con la quema p\u00fablica de las obras de Galeno y la denuncia de los maestros \u00e1rabes, cuyas ense\u00f1anzas eran seguidas en general. Tambi\u00e9n se burl\u00f3 de la tradici\u00f3n al ende\u00f1ar en\u00a0 alem\u00e1n en lugar del lat\u00edn. Su desaf\u00edo a la tradici\u00f3n, adem\u00e1s de su arrogancia, la vanidad y la embriaguez, provoc\u00f3 la animosidad m\u00e1s amarga de la facultad de regular, y se vio obligado a abandonar la universidad en 1528.<\/p>\n<p><a href=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2012\/09\/b605a838036e13947e8dd11697cdd276.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-113694 lazyload\" style=\"--smush-placeholder-width: 178px; --smush-placeholder-aspect-ratio: 178\/250;margin: 6px;\" title=\"Paracelso\" data-src=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2012\/09\/b605a838036e13947e8dd11697cdd276-213x300.jpg\" alt=\"Paracelso\" width=\"178\" height=\"250\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><noscript><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-113694\" style=\"margin: 6px;\" title=\"Paracelso\" src=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2012\/09\/b605a838036e13947e8dd11697cdd276-213x300.jpg\" alt=\"Paracelso\" width=\"178\" height=\"250\" \/><\/noscript><\/a>Volvi\u00f3 a sus andanzas. Dondequiera que iba, causaba un estado de odio violento, no del todo inmerecida. En Salzburgo se ofendi\u00f3 y fue arrojado desde una ventana por los servidores de un m\u00e9dico, muri\u00f3 de la ca\u00edda. Su tumba se encuentra en la Iglesia de San Sebasti\u00e1n en Salzburgo.<\/p>\n<p>Fue el primer m\u00e9dico en describir correctamente una serie de enfermedades graves, como la tuberculosis, una enfermedad de los pulmones.\u00a0Fruto de su propia experiencia, escribi\u00f3 la que ser\u00eda su obra m\u00e1s importante, \u201cEl gran libro de la cirug\u00eda\u201c.<\/p>\n<p>A pesar de su turbulenta vida y m\u00e9todos de charlat\u00e1n, Paracelso ejerci\u00f3 una profunda influencia en las creencias m\u00e9dicas de su \u00e9poca y de siglos posteriores. Golpe\u00f3 a los puntos d\u00e9biles del sistema imperante de la medicina y destruy\u00f3 la \u201cpatolog\u00eda humoral\u201d (que fue fundada en la creencia de que las enfermedades depend\u00eda de un exceso o deficiencia de la bilis, la flema o sangre), y ense\u00f1\u00f3 que las enfermedades eran reales entidades y deb\u00edan ser combatidos con recursos espec\u00edficos.<\/p>\n<p>Mejor\u00f3 la\u00a0 farmacolog\u00eda y la terap\u00e9utica, introdujo nuevos remedios (opio, mercurio, azufre, hierro, ars\u00e9nico, etc), hizo algunos nuevos compuestos qu\u00edmicos, y se esforz\u00f3 por reducir la pr\u00e1ctica de sobredosis. Se le atribuyen un gran n\u00famero de obras de medicina, muchos de los cuales fueron escritas por sus seguidores. Marx admite que s\u00f3lo el 10 como genuinas: haser 24. Su obra m\u00e1s conocida es Die grosse Wundartzney (1530). Ediciones de obras de sus escritos aparecieron en Basilea, Estrasburgo, Ginebra y Munich. La primero traducci\u00f3n al Ingl\u00e9s fue editada por John Hester y apareci\u00f3 en Londres en 1596 bajo el t\u00edtulo Ciento un\u00a0 experimentos Fowrteene y curaciones, entre otras.<\/p>\n<p>Astr\u00f3logo consumado, crey\u00f3 firmemente en las interacciones entre el macrocosmos y el microcosmos, al punto de afirmar que \u201cno se puede ejercer la medicina sin mirar a los astros\u201c.<\/p>\n<p>Su rebeld\u00eda ante el conocimiento establecido le llev\u00f3 a quemar libros de Avicena y Galeno, entre otros, delante de la Universidad de Basilea\u2026<\/p>\n<p>Uno de sus legados m\u00e1s famosos han sido las \u201cSiete reglas para una vida con sentido\u201d donde demuestra una visi\u00f3n hol\u00edstica y moderna de la salud.<\/p>\n<p><ul id='postTabs_ul_113667' class='postTabs' style='display:none'>\n<li id='postTabs_li_0_113667' class='postTabs_curr'><a  id=\"113667_0\" onMouseOver=\"posTabsShowLinks('Paracelso'); return true;\"  onMouseOut=\"posTabsShowLinks();\"  class='postTabsLinks'>Paracelso<\/a><\/li>\n<li id='postTabs_li_1_113667' ><a  id=\"113667_1\" onMouseOver=\"posTabsShowLinks('Libro'); return true;\"  onMouseOut=\"posTabsShowLinks();\"  class='postTabsLinks'>Libro<\/a><\/li>\n<li id='postTabs_li_2_113667' ><a  id=\"113667_2\" onMouseOver=\"posTabsShowLinks('El hom\u00fanculo de Paracelso'); return true;\"  onMouseOut=\"posTabsShowLinks();\"  class='postTabsLinks'>El hom\u00fanculo de Paracelso<\/a><\/li>\n<li id='postTabs_li_3_113667' ><a  id=\"113667_3\" onMouseOver=\"posTabsShowLinks('Las 7 reglas de Paracelso'); return true;\"  onMouseOut=\"posTabsShowLinks();\"  class='postTabsLinks'>Las 7 reglas de Paracelso<\/a><\/li>\n<\/ul>\n\n<div class='postTabs_divs postTabs_curr_div' id='postTabs_0_113667'>\n<span class='postTabs_titles'><b>Paracelso<\/b><\/span><\/p>\n<p style=\"text-align: center;\"><embed width=\"500\" height=\"375\" src=\"http:\/\/www.youtube.com\/embed\/FkSOyrxWzxU\" frameborder=\"0\"><\/embed><\/p>\n<p><\/div>\n\n<div class='postTabs_divs' id='postTabs_1_113667'>\n<span class='postTabs_titles'><b>Libro<\/b><\/span><\/p>\n<p style=\"text-align: center;\"><embed style=\"width: 500px; height: 600px;\" src=\"http:\/\/www.fraternidaderosacruz.org\/ParacelsoOperaOmnia.pdf\"><\/embed><\/p>\n<p><\/div>\n\n<div class='postTabs_divs' id='postTabs_2_113667'>\n<span class='postTabs_titles'><b>El hom\u00fanculo de Paracelso<\/b><\/span><\/p>\n<p style=\"text-align: center;\"><embed width=\"500\" height=\"375\" src=\"http:\/\/www.youtube.com\/embed\/Gojo40TAsfk\" frameborder=\"0\"><\/embed><\/p>\n<p><\/div>\n\n<div class='postTabs_divs' id='postTabs_3_113667'>\n<span class='postTabs_titles'><b>Las 7 reglas de Paracelso<\/b><\/span><\/p>\n<p style=\"text-align: center;\"><embed width=\"500\" height=\"375\" src=\"http:\/\/www.youtube.com\/embed\/npDOGBbcPUw\" frameborder=\"0\"><\/embed><\/p>\n<p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Alquimista, m\u00e9dico y astr\u00f3logo suizo. Sus \u201cSiete reglas para una vida con sentido\u201d demuestran una visi\u00f3n hol\u00edstica y moderna de la salud. <a href=\"http:\/\/www.moonmentum.com\/blog\/?p=113667\">Ver m\u00e1s&#8230;<\/a><\/p>\n","protected":false},"author":6,"featured_media":113694,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8198],"tags":[1621,1623,8761,14186,605,882,8266,14210,10755,11595],"class_list":{"0":"post-113667","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-multimedia","8":"tag-alquimista","9":"tag-astrologo","10":"tag-conflicto","11":"tag-controversia","12":"tag-escritor","13":"tag-medico","14":"tag-quimico","15":"tag-reglas","16":"tag-sentido","17":"tag-suizo"},"_links":{"self":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts\/113667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/comments?post=113667"}],"version-history":[{"count":0,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts\/113667\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/media\/113694"}],"wp:attachment":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/media?parent=113667"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/categories?post=113667"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/tags?post=113667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}