{"id":116040,"date":"2012-10-15T00:05:59","date_gmt":"2012-10-15T04:35:59","guid":{"rendered":"http:\/\/www.moonmentum.com\/blog\/?p=116040"},"modified":"2013-07-09T13:52:05","modified_gmt":"2013-07-09T18:22:05","slug":"el-cargador-de-serpientes-arriba-del-horizonte","status":"publish","type":"post","link":"https:\/\/moonmentum.com\/blog\/actualidad\/observatorio-moonmentum\/el-cargador-de-serpientes-arriba-del-horizonte\/","title":{"rendered":"El cargador de serpientes arriba del horizonte"},"content":{"rendered":"<p><a href=\"http:\/\/www.moonmentum.com\/blog\/energia-protagonica\/observatorio-moonmentum\/el-cargador-de-serpientes-arriba-del-horizonte\/attachment\/observatorio-29\/\" rel=\"attachment wp-att-116462\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-116462 lazyload\" style=\"--smush-placeholder-width: 242px; --smush-placeholder-aspect-ratio: 242\/250;float: left; margin: 6px; border: 0px;\" title=\"observatorio\" alt=\"observatorio\" data-src=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2012\/10\/6fa5c60628804a1b10f25481c1f91165.jpg\" width=\"242\" height=\"250\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><noscript><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-116462\" style=\"float: left; margin: 6px; border: 0px;\" title=\"observatorio\" alt=\"observatorio\" src=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2012\/10\/6fa5c60628804a1b10f25481c1f91165.jpg\" width=\"242\" height=\"250\" \/><\/noscript><\/a>Al caer la noche, Ofiuco, el cargador de serpientes, est\u00e1 muy alto en el oeste, flanqueado por las mitades divididas de la serpiente. Ninguna de las estrellas es brillante, pero Ofiuco es grande, as\u00ed que si usted mira hacia arriba del horizonte, usted lo tendr\u00e1 directamente enfrente<sup class='footnote'><a href='#fn-116040-1' id='fnref-116040-1' onclick='return fdfootnote_show(116040)'>1<\/a><\/sup>.<\/p>\n<p>Phiuchus fue hijo ileg\u00edtimo de Apolo con una ninfa llamada Coronis, Asclepios, aprendi\u00f3 medicina del Centauro Caronte. Despu\u00e9s fue el cirujano de los Argonautas, navegando con ellos en la nave Argos tratando de devolver la vida a la gente, incluidos el hijo del rey Minos de Creta.<!--more--><\/p>\n<p>Fue despu\u00e9s de que Asclepios tratara de revivir a Ori\u00f3n, picado por el Escorpi\u00f3n cuando Plut\u00f3n se quej\u00f3 a Zeus que si Asclepios actuaba de esta forma haciendo inmortal a la gente, el robar\u00eda todo el pueblo de Hades. Y as\u00ed fue que Zeus no permiti\u00f3 m\u00e1s inmortalidades y envi\u00f3 un rallo para matar a Asclepios.<\/p>\n<p>Zeus puso a Asclepios en un lugar del cielo cercano a la Serpiente\u00a0 (Serpens Cauda y Serpens Caput) porque esta representaba la vida renovada.<\/p>\n<p>Mientras que el culto a Asclepios comenz\u00f3 en Tesalia, se construyeron templos a trav\u00e9s de toda Grecia, llegando a Roma alrededor del a\u00f1o 300 a. C.<\/p>\n<p>Las antiguas esculturas lo muestran con el pecho descubierto y portando una larga capa y asiendo un bast\u00f3n con una serpiente enrollada (quiz\u00e1 el precursor del moderno s\u00edmbolo de la medicina).\u00a0\u00a0\u00a0\u00a0 Por eso, Ofiuco est\u00e1 situado en medio de la constelaci\u00f3n de Serpens (la Serpiente) sumergi\u00e9ndose su zona sur en la V\u00eda L\u00e1ctea, por lo que se pueden disfrutar muchos objetos de cielo profundo.<\/p>\n<p><span style=\"color: #888888;\"><em>\u00bf<\/em><em>Cu\u00e1ntas veces te detienes a observar lo que el cielo cada noche coloca en cartelera?\u2026 Recuerda el axioma que dice \u201cComo es arriba\u2026 es abajo\u201d\u2026 El cielo y las estrellas no son un adorno\u2026 son una realidad.<\/em><em><\/em><\/span><\/p>\n<p><span style=\"color: #888888;\"><em>Observar<\/em><em> nos conecta en un 30% con la energ\u00eda del Universo.<br \/>\nImitar lo observado\u00a0 nos conecta en un 70% con la energ\u00eda del Universo\u2026<br \/>\nEmular lo observado nos convierte en la energ\u00eda.<\/em><\/span><\/p>\n<p><sup><span style=\"color: #888888;\"><strong>Fuentes:<\/strong> radiouniverso.org, mallorcaweb.net<\/span><br \/>\n<span style=\"color: #888888;\"><strong>Imagen:<\/strong><strong> <\/strong>serpent77.wordpress.com<\/span><\/sup><\/p>\n<div class='footnotes' id='footnotes-116040'>\n<div class='footnotedivider'><\/div>\n<ol>\n<li id='fn-116040-1'> Nota:\u00a0Esta informaci\u00f3n s\u00f3lo es v\u00e1lida para el Hemisferio Norte. <span class='footnotereverse'><a href='#fnref-116040-1'>&#8617;<\/a><\/span><\/li>\n<\/ol>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Al caer la noche, Ofiuco, el cargador de serpientes, est\u00e1 muy alto en el oeste, flanqueado por las mitades divididas de la serpiente. Ninguna de las estrellas es brillante, pero Ofiuco es grande, as\u00ed que si usted mira hacia arriba del horizonte, usted lo tendr\u00e1 directamente enfrente1. Phiuchus fue hijo ileg\u00edtimo de Apolo con una [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":116461,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[14378,3514],"class_list":{"0":"post-116040","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-observatorio-moonmentum","8":"tag-el-cargador-de-serpientes","9":"tag-ofiuco"},"_links":{"self":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts\/116040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/comments?post=116040"}],"version-history":[{"count":0,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts\/116040\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/media\/116461"}],"wp:attachment":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/media?parent=116040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/categories?post=116040"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/tags?post=116040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}