{"id":12399,"date":"2009-11-21T00:06:33","date_gmt":"2009-11-21T04:36:33","guid":{"rendered":"http:\/\/www.moonmentum.com\/blog\/?p=12399"},"modified":"2009-11-20T18:17:48","modified_gmt":"2009-11-20T22:47:48","slug":"orion-esta-a-la-vista","status":"publish","type":"post","link":"https:\/\/moonmentum.com\/blog\/actualidad\/observatorio-moonmentum\/orion-esta-a-la-vista\/","title":{"rendered":"Ori\u00f3n est\u00e1 a la vista"},"content":{"rendered":"<p><a href=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2009\/11\/c789a8a815b9cba06a17a8528731ae61.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-12400 lazyload\" style=\"--smush-placeholder-width: 225px; --smush-placeholder-aspect-ratio: 225\/300;border: 0pt none; margin: 6px; float: left;\" title=\"orion\" data-src=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2009\/11\/c789a8a815b9cba06a17a8528731ae61-225x300.jpg\" alt=\"orion\" width=\"225\" height=\"300\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><noscript><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-12400\" style=\"border: 0pt none; margin: 6px; float: left;\" title=\"orion\" src=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2009\/11\/c789a8a815b9cba06a17a8528731ae61-225x300.jpg\" alt=\"orion\" width=\"225\" height=\"300\" \/><\/noscript><\/a>Ori\u00f3n, el cazador, est\u00e1 a la vista bajo en el este como a las 10 pm busque a su cintur\u00f3n. Una l\u00ednea corta de tres estrellas que se encuentra casi directamente arriba del horizonte. La brillante y anaranjada Betelgeuse est\u00e1 hacia la izquierda del cintur\u00f3n, con la azul-blanca Rigel hacia la derecha.<\/p>\n<p>Las noches de noviembre son una buena \u00e9poca para observar la V\u00eda L\u00e1ctea, la cual es el brillo combinado de millones de estrellas en el disco de nuestra galaxia. <!--more-->Se arquea de este a oeste, hundi\u00e9ndose hacia el horizonte del norte. Usted necesitar\u00e1 un cielo oscuro para ver la V\u00eda L\u00e1ctea.<\/p>\n<p><strong>Fuente: <\/strong><a href=\"http:\/\/mcdonaldobservatory.org\/\">Observatorio McDonald<\/a><\/p>\n<p>\u00bfCu\u00e1ntas veces usted se detiene a observar lo que el cielo cada noche coloca en cartelera?&#8230; Recuerde el axioma que dice \u201cComo es arriba\u2026es abajo\u201d\u2026<\/p>\n<p>El cielo y las estrellas no son un adorno\u2026 son una realidad.<\/p>\n<p><strong>Observar nos conecta en un 30%<\/strong> con la energ\u00eda del Universo.<strong><br \/>\nImitar lo observado\u00a0 nos conecta en un 70%<\/strong> con la energ\u00eda del Universo&#8230;<strong><br \/>\nEmular<\/strong> lo observado nos convierte en la energ\u00eda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ori\u00f3n, el cazador, est\u00e1 a la vista bajo en el este como a las 10 pm busque a su cintur\u00f3n. Una l\u00ednea corta de tres estrellas que se encuentra casi directamente arriba del horizonte. La brillante y anaranjada Betelgeuse est\u00e1 hacia la izquierda del cintur\u00f3n, con la azul-blanca Rigel hacia la derecha. Las noches de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":12400,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[919,837,17199,402,17187,1243],"class_list":["post-12399","post","type-post","status-publish","format-standard","has-post-thumbnail","category-observatorio-moonmentum","tag-cielo","tag-constelaciones","tag-mirando-las-estrellas","tag-observatorio-mcdonald","tag-observatorio-moonmentum","tag-orion"],"_links":{"self":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts\/12399","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/comments?post=12399"}],"version-history":[{"count":0,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts\/12399\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/media\/12400"}],"wp:attachment":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/media?parent=12399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/categories?post=12399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/tags?post=12399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}