{"id":126039,"date":"2012-12-31T00:06:23","date_gmt":"2012-12-31T04:36:23","guid":{"rendered":"http:\/\/www.moonmentum.com\/blog\/?p=126039"},"modified":"2012-12-31T07:46:43","modified_gmt":"2012-12-31T12:16:43","slug":"vision-nos-inspira-nuestra-semilla","status":"publish","type":"post","link":"https:\/\/moonmentum.com\/blog\/efemerides\/semilla-de-la-semana\/vision-nos-inspira-nuestra-semilla\/","title":{"rendered":"Visi\u00f3n nos inspira nuestra Semilla"},"content":{"rendered":"<p><em><a href=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2012\/12\/69ce89103a66c66e9a758c412155ce3e.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-127039 lazyload\" style=\"--smush-placeholder-width: 250px; --smush-placeholder-aspect-ratio: 250\/195;float: left; margin: 6px; border: 0px;\" title=\"semilla1\" data-src=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2012\/12\/69ce89103a66c66e9a758c412155ce3e-300x234.jpg\" alt=\"semilla1\" width=\"250\" height=\"195\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><noscript><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-127039\" style=\"float: left; margin: 6px; border: 0px;\" title=\"semilla1\" src=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2012\/12\/69ce89103a66c66e9a758c412155ce3e-300x234.jpg\" alt=\"semilla1\" width=\"250\" height=\"195\" \/><\/noscript><\/a>\u00abEl medio es el mensaje\u00bb<\/em>.<br \/>\n<strong>Herbert Marshall McLuhan<\/strong><strong><br \/>\n<\/strong><em> <\/em><\/p>\n<p><em>Cada d\u00eda hay en el Universo una estela dejada por la acci\u00f3n de otros seres humanos que al igual que nosotros buscaban la excelencia. Hoy esa\u00a0 estela o\u00a0 \u201c<\/em><a href=\"http:\/\/www.moonmentum.com\/blog\/category\/efemerides\/semilla-del-dia\/\" target=\"_blank\"><em>semilla del d\u00eda<\/em><\/a><em>\u201d fue sembrada por\u2026<\/em><em><\/em><\/p>\n<p><strong>Herbert Marshall McLuhan<\/strong>, es reverenciado como uno de los fundadores de los estudios sobre los medios, y ha pasado a la posteridad como uno de los grandes visionarios de la presente y futura sociedad de la informaci\u00f3n. Durante el final de los a\u00f1os 60 y principios de los 70, McLuhan acu\u00f1\u00f3 el t\u00e9rmino <a title=\"Aldea global\" href=\"http:\/\/es.wikipedia.org\/wiki\/Aldea_global\" target=\"_blank\"><strong><em>aldea global<\/em><\/strong><\/a><strong> <\/strong>para describir la interconexi\u00f3n humana a escala global generada por los medios electr\u00f3nicos de comunicaci\u00f3n. Es famosa su sentencia <em>\u00abel medio es el mensaje\u00bb<\/em>.<!--more--><\/p>\n<p>Un total de nueve universidades le concedieron doctorados honoris causa: University of Windsor (1965), Assumption University (1966), University of Manitoba (1967), Simon Fraser University (1967), Grinnell University (1967), St. John Fisher College (1969), University of Alberta (1971), University of Western Ontario (1972), University of Toronto (1977).<strong> <\/strong><\/p>\n<p>McLuhan es el creador de numerosos conceptos hoy muy populares acerca de los medios de difusi\u00f3n masiva y la sociedad de la informaci\u00f3n, tales como la <em>Galaxia Gutenberg<\/em>, la <em>Aldea global<\/em>, la diferenciaci\u00f3n entre medios <em>fr\u00edos<\/em> y <em>calientes<\/em> y la descripci\u00f3n de los medios de comunicaci\u00f3n como <em>extensiones<\/em> de la persona.<\/p>\n<p>\u00bfCu\u00e1l era el particular enfoque de McLuhan? Esencialmente, podr\u00eda decirse que no ten\u00eda ninguno. La aproximaci\u00f3n de McLuhan a un determinado problema part\u00eda de negar un punto fijo, puesto que la comprensi\u00f3n requiere siempre, para \u00e9l, un enfoque multidimensional. Con total libertad, sus escritos carecen de argumentaciones complejas o de tesis alguna que se desarrolle linealmente a lo largo de sus p\u00e1ginas.<\/p>\n<p>Es innegable que McLuhan fue, en efecto, un hombre libre. Su l\u00e1pida reza, con tipograf\u00eda digital:<\/p>\n<p><em>La verdad nos har\u00e1 libres.<\/em> (Cita b\u00edblica: <em>Veritas liberabit nos.<\/em>)<\/p>\n<p>Diarios y revistas lo recordaron a su muerte con calificativos como <em>M\u00edstico de la Aldea Electr\u00f3nica<\/em> o <em>El m\u00e1s hippie entre los acad\u00e9micos y el m\u00e1s acad\u00e9mico entre los hippies<\/em>.<\/p>\n<p><sup><span style=\"color: #888888;\">Foto: digigen.co.uk<\/span><\/sup><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abEl medio es el mensaje\u00bb. Herbert Marshall McLuhan Cada d\u00eda hay en el Universo una estela dejada por la acci\u00f3n de otros seres humanos que al igual que nosotros buscaban la excelencia. Hoy esa\u00a0 estela o\u00a0 \u201csemilla del d\u00eda\u201d fue sembrada por\u2026 Herbert Marshall McLuhan, es reverenciado como uno de los fundadores de los estudios [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":127039,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[343,481,17184],"class_list":{"0":"post-126039","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-semilla-de-la-semana","8":"tag-lourdes-mendez","9":"tag-semilla","10":"tag-semilla-de-la-semana"},"_links":{"self":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts\/126039","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/comments?post=126039"}],"version-history":[{"count":0,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts\/126039\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/media\/127039"}],"wp:attachment":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/media?parent=126039"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/categories?post=126039"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/tags?post=126039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}