{"id":129125,"date":"2013-01-18T00:05:58","date_gmt":"2013-01-18T04:35:58","guid":{"rendered":"http:\/\/www.moonmentum.com\/blog\/?p=129125"},"modified":"2013-04-09T11:14:30","modified_gmt":"2013-04-09T15:44:30","slug":"a-los-pies-de-geminis","status":"publish","type":"post","link":"https:\/\/moonmentum.com\/blog\/actualidad\/observatorio-moonmentum\/a-los-pies-de-geminis\/","title":{"rendered":"A los pies de G\u00e9minis"},"content":{"rendered":"<p><a href=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2013\/01\/i1wpcom_11.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-129252 lazyload\" style=\"--smush-placeholder-width: 250px; --smush-placeholder-aspect-ratio: 250\/178;float: left; margin: 6px; border: 0px;\" title=\"i1.wp.com.1.1\" data-src=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2013\/01\/i1.wp.com_.1.1-300x214.jpg\" alt=\"i1.wp.com.1.1\" width=\"250\" height=\"178\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><noscript><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-129252\" style=\"float: left; margin: 6px; border: 0px;\" title=\"i1.wp.com.1.1\" src=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2013\/01\/i1.wp.com_.1.1-300x214.jpg\" alt=\"i1.wp.com.1.1\" width=\"250\" height=\"178\" \/><\/noscript><\/a>El c\u00famulo estelar M35 est\u00e1 en el oriente al caer la noche, a los pies de G\u00e9minis. A pesar de que el c\u00famulo est\u00e1 a m\u00e1s de 2,500 a\u00f1os luz de distancia, bajo cielos oscuros es observable a simple vista como un parche borroso de luz. Unos binoculares mejorar\u00e1n la vista.<\/p>\n<p>Dos c\u00famulos estelares abiertos en la Constelaci\u00f3n de G\u00e9minis. M35 y NGC 2158, vecinas en nuestra V\u00eda L\u00e1ctea, y contienen unas 2.500 estrellas cada uno, seg\u00fan indic\u00f3 APOD.<\/p>\n<p>Estos c\u00famulos estelares pueden estar distintas o lejanos, ser j\u00f3venes o antiguos, extendidos o compactos, como puede distinguirse en la imagen de Willasch. Como ocurre con las formaciones estelares, el color azul nos muestra la presencia de estrellas j\u00f3venes, nacientes o en formaci\u00f3n, mientras que del amarillo al rojizo podemos advertir que se trata de estrellas antiguas o en v\u00edas de extinci\u00f3n.<!--more--><\/p>\n<p>As\u00ed, M35, arriba a la izquierda, est\u00e1 relativamente cerca de nosotros, a 2.800 a\u00f1os luz de distancia, y es un c\u00famulo relativamente joven, de unos 150 millones de a\u00f1os, con unas 2.500 estrellas distribuidas en un espacio difuso de 30 a\u00f1os luz de ancho.<\/p>\n<p>Tambi\u00e9n puede observarse, otro c\u00famulo m\u00e1s compacto, NGC 2158, que est\u00e1 cuatro veces m\u00e1s lejano que M35, es unos 10 a\u00f1os m\u00e1s antiguo, y como se aprecia es mucho m\u00e1s compacto, si bien tiene casi la misma cantidad de estrellas que aquel.<\/p>\n<p><span style=\"font-size: large;\"><strong>C\u00famulo abierto M35<\/strong><\/span><\/p>\n<p>Messier 35 (tambi\u00e9n conocido como M 35, o NGC 2168) es un c\u00famulo abierto en la constelaci\u00f3n de G\u00e9minis. Fue descubierto por Philippe Loys de Ch\u00e9seaux en 1745 y redescubierto independientemente por John Bevis antes de 1750.<\/p>\n<p>M35 contiene varios cientos de estrellas (Ake Wallenquist ha contado 120 con magnitud aparente superior a 13) dispersas en el \u00e1rea que cubre la luna llena (28 arcmin). El Sky Catalogue 2000.0 y la primera edici\u00f3n de Uranometr\u00eda 2000.0 conceden 200 miembros. A una distancia de unos 2800 a\u00f1os luz de la Tierra corresponde a un di\u00e1metro de cerca de 24 a\u00f1os luz. El c\u00famulo tiene una edad de entre 95 y 110 millones de a\u00f1os y contiene algunas estrellas que ya han abandonado la secuencia principal, entre las que se incluyen varias gigantes amarillas y naranjas de tipo espectral G tard\u00edo o K temprano. Su tipo Trumpler es III 3 r, y se aproxima a nosotros a raz\u00f3n de 5 km\/s.<strong> <\/strong><\/p>\n<p><strong> <\/strong><\/p>\n<p>Nota: Esta informaci\u00f3n s\u00f3lo es v\u00e1lida para el Hemisferio Norte.<\/p>\n<p><span style=\"color: #888888;\"><em>\u00bfCu\u00e1ntas veces te detienes a observar lo que el cielo cada noche coloca en cartelera?\u2026 Recuerda el axioma que dice \u201cComo es arriba\u2026 es abajo\u201d\u2026 El cielo y las estrellas no son un adorno\u2026 son una realidad.<\/em><\/span><\/p>\n<p><span style=\"color: #888888;\"><em>Observar nos conecta en un 30% con la energ\u00eda del Universo.<br \/>\nImitar lo observado\u00a0 nos conecta en un 70% con la energ\u00eda del Universo\u2026<br \/>\nEmular lo observado nos convierte en la energ\u00eda.<\/em><\/span><\/p>\n<p><sup><span style=\"color: #888888;\"> <strong>Fuentes:<\/strong> radiouniverso.org, notaspampeanas.com, es.wikipedia.org<\/span><br \/>\n<span style=\"color: #888888;\"> <strong>Imagen: <\/strong>notaspampeanas.com<\/span><\/sup><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El c\u00famulo estelar M35 est\u00e1 en el oriente al caer la noche, a los pies de G\u00e9minis. A pesar de que el c\u00famulo est\u00e1 a m\u00e1s de 2,500 a\u00f1os luz de distancia, bajo cielos oscuros es observable a simple vista como un parche borroso de luz. Unos binoculares mejorar\u00e1n la vista. Dos c\u00famulos estelares abiertos [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":129252,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[14998,919,17209,2486,593,17199,401,3514,496,527],"class_list":{"0":"post-129125","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-observatorio-moonmentum","8":"tag-cumulo-abierto-m35","9":"tag-cielo","10":"tag-geminis","11":"tag-hercules","12":"tag-luna","13":"tag-mirando-las-estrellas","14":"tag-observatorio-mc-donald","15":"tag-ofiuco","16":"tag-sol","17":"tag-universo"},"_links":{"self":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts\/129125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/comments?post=129125"}],"version-history":[{"count":0,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts\/129125\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/media\/129252"}],"wp:attachment":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/media?parent=129125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/categories?post=129125"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/tags?post=129125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}