{"id":1292,"date":"2009-04-20T12:46:40","date_gmt":"2009-04-20T17:16:40","guid":{"rendered":"http:\/\/www.elpulsodeltiempo.com\/timepulse\/?p=1292"},"modified":"2009-04-20T12:46:40","modified_gmt":"2009-04-20T17:16:40","slug":"efemerides-pronostico-2456","status":"publish","type":"post","link":"https:\/\/moonmentum.com\/blog\/efemerides\/efemerides-pronostico-2456\/","title":{"rendered":"Efem\u00e9rides \/ Pron\u00f3stico # 2456"},"content":{"rendered":"<p style=\"TEXT-ALIGN: center\"><em><strong>\u00abSentido de Pertenencia\u00bb<\/strong><\/em><\/p>\n<p style=\"TEXT-ALIGN: center\">Cuanto m\u00e1s posee el hombre, menos se posee a s\u00ed mismo.<\/p>\n<p style=\"TEXT-ALIGN: center\"><em><strong>Arturo\u00a0Graf<\/strong><\/em><\/p>\n<p style=\"TEXT-ALIGN: center\"><a href=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2009\/04\/470b5ebac62e0f98c79b1606eecca105.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1312 lazyload\" style=\"--smush-placeholder-width: 92px; --smush-placeholder-aspect-ratio: 92\/131;border: 0px;\" title=\"arturo-graf\" data-src=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2009\/04\/470b5ebac62e0f98c79b1606eecca105.jpg\" alt=\"arturo-graf\" width=\"92\" height=\"131\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><noscript><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1312\" style=\"border: 0px;\" title=\"arturo-graf\" src=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2009\/04\/470b5ebac62e0f98c79b1606eecca105.jpg\" alt=\"arturo-graf\" width=\"92\" height=\"131\" \/><\/noscript><\/a><\/p>\n<p style=\"TEXT-ALIGN: justify\"><strong><span style=\"font-size: small;\">Efem\u00e9rides\u00a0\u00a0\u00a0<\/span>\u00a0\u00a0\u00a0<\/strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/p>\n<p style=\"TEXT-ALIGN: justify\">\u00a0<strong>Abril<\/strong> es el cuarto mes del a\u00f1o en el Calendario Gregoriano y tiene 30 d\u00edas. <!--more-->Los antiguos romanos le llamaban Aprilis en lat\u00edn.<\/p>\n<p style=\"TEXT-ALIGN: justify\">\u00a0<strong>Abril<\/strong>:\u00a0 Del lat\u00edn \u00abaperire\u00bb que significa abrir. Durante este mes se abren las flores y estalla la primavera. Hay historiadores que creen que puede estar dedicado tambi\u00e9n a \u00abaper\u00bb un jabal\u00ed que era venerado por los romanos o que su ra\u00edz etimol\u00f3gica provenga de \u00abaparas\u00bb, una palabra oriental que significa \u00absiguiente\u00bb, o sea, siguiente al primer mes, ya que para los romanos, este era el segundo mes del a\u00f1o.<\/p>\n<p style=\"TEXT-ALIGN: justify\">El <strong>20 de abril<\/strong> es el 110\u00ba d\u00eda del a\u00f1o del calendario gregoriano y el 111\u00ba en los a\u00f1os bisiestos. Quedan 255 d\u00edas para finalizar el a\u00f1o.\u00a0<\/p>\n<p style=\"TEXT-ALIGN: justify\"><span style=\"font-size: small;\"><strong>Acontecimientos:<\/strong><\/span><\/p>\n<p style=\"TEXT-ALIGN: justify\"><strong>1775<\/strong> &#8211; Estados Unidos: Las tropas brit\u00e1nicas sitian la ciudad de Boston.<br \/>\n<strong>1792<\/strong> &#8211; Europa: Francia le declara la guerra a Austria.<br \/>\n<strong>1810<\/strong> &#8211; Virreinato de Nueva Granada: La Junta de Gobierno de Caracas proclama la existencia de una soberan\u00eda nacional desligada de Espa\u00f1a.<br \/>\n<strong>1862<\/strong> &#8211; Se completa el primer \u00e9xamen de pasteurizaci\u00f3n. Se estima que hay un bill\u00f3n de personas que no tienen acceso a agua limpia \u00bfque se recomienda? La \u00fanica recomendaci\u00f3n que se hace es la de hacer hervir el agua, a veces hasta 10 minutos. Esto se ha sabido de la \u00e9poca de Luis Pasteur hace ya 130 a\u00f1os que demostr\u00f3 que hervir el agua es un m\u00e9todo muy efectivo para matar a los microbios del agua y de la leche.<br \/>\n<strong>1871<\/strong> &#8211; Estados Unidos: Se declara una ley que suprime al Ku-Klux-Klan.<br \/>\n<strong>1902<\/strong> &#8211; Los cient\u00edficos franceses Pierre y Marie Curie refinan cloruro de radio.<br \/>\n<strong>1992<\/strong> &#8211; En el estadio Wembley de Londres se realiza el Tributo a Freddie Mercury para la Prevenci\u00f3n del SIDA. Participan los restantes integrantes de Queen, y artistas invitados como George Michael, David Bowie, Annie Lennox, Lisa Stansfield, Paul Young, Guns N&#8217;Roses, Elton John, Robert Plant, Metallica y Seal, entre otros.<br \/>\n<strong>1999<\/strong> &#8211; <em>Masacre del instituto Columbine<\/em>: Eric Harris y Dylan Klebold, dos estudiantes del instituto Columbine, en Estados Unidos, ingresan al mismo y asesinan a 12 estudiantes y un profesor para luego suicidarse.<br \/>\n<strong>2005<\/strong> &#8211; Ecuador: Es derrocado el presidente Lucio Guti\u00e9rrez, el Congreso Ecuatoriano designa a Alfredo Palacio como sucesor.<\/p>\n<p style=\"TEXT-ALIGN: justify\"><strong><span style=\"font-size: small;\">Nacimientos:<\/span><\/strong><\/p>\n<p style=\"TEXT-ALIGN: justify\"><strong>1586<\/strong> &#8211; Isabel Flores, (<em>Santa Rosa de Lima<\/em>), religiosa peruana.<br \/>\n<strong>1889<\/strong> &#8211; Adolf Hitler, pol\u00edtico alem\u00e1n de origen austr\u00edaco, que estableci\u00f3 un r\u00e9gimen nacionalsocialista en el que recibi\u00f3 el t\u00edtulo de Reichskanzler (canciller imperial) y <em>F\u00fchrer<\/em> (caudillo, l\u00edder o gu\u00eda).<br \/>\n<strong>1893<\/strong> &#8211; Joan Mir\u00f3, pintor espa\u00f1ol, considerado uno de los m\u00e1ximos representantes del surrealismo. En su obra reflej\u00f3 su inter\u00e9s en el subconsciente, en lo \u00abinfantil\u00bb y en su pa\u00eds.<br \/>\n<strong>1904<\/strong> &#8211; George R. Stibitz, cient\u00edfico estadounidense. En la actualidad se entrega anualmente el premio <em>George R Stibitz Computer Pioneer del American Computer Museum<\/em>, premio que destaca a los pioneros en el campo de la investigaci\u00f3n inform\u00e1tica.<\/p>\n<p style=\"TEXT-ALIGN: justify\"><strong><span style=\"font-size: small;\">Fallecimientos:<\/span><\/strong><\/p>\n<p style=\"TEXT-ALIGN: justify\"><strong>1472<\/strong> &#8211; Leon Battista Alberti, fue un arquitecto, matem\u00e1tico y poeta italiano. Adem\u00e1s de estas actividades principales, tambi\u00e9n fue cript\u00f3grafo, ling\u00fcista, fil\u00f3sofo, m\u00fasico y arque\u00f3logo. Es una de las figuras art\u00edsticas m\u00e1s polifac\u00e9ticas del Renacimiento.<br \/>\n<strong>1912<\/strong> -Pedro Lira, pintor chileno. pintor chileno. Exteno promotor del arte en el pa\u00eds y considerado como uno de los principales artistas del siglo XIX en Chile, fue uno de los fundadores del Museo Nacional de Bellas Artes.<br \/>\n<strong>1912<\/strong> &#8211; Bram Stoker, escritor irland\u00e9s, c\u00e9lebre por su novela de terror <em>Dr\u00e1cula<\/em>, una de las obras m\u00e1s famosas de la literatura g\u00f3tica. Fundamentalmente es reconocido en el g\u00e9nero literario por su pseud\u00f3nimo Bram Stoker.<br \/>\n<strong>1918<\/strong> &#8211; Carl Ferdinand Braun, f\u00edsico alem\u00e1n, premio Nobel de F\u00edsica en 1909. <em>(junto con Marconi, \u00abpor sus contribuciones al desarrollo de la telegraf\u00eda sin hilos\u00bb).<br \/>\n<\/em><\/p>\n<p style=\"TEXT-ALIGN: justify\"><span style=\"font-size: small;\"><strong>Fiestas<\/strong>:<\/span><\/p>\n<p style=\"TEXT-ALIGN: justify\">D\u00eda internacional de la Marihuana.<\/p>\n<p style=\"TEXT-ALIGN: justify\">\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abSentido de Pertenencia\u00bb Cuanto m\u00e1s posee el hombre, menos se posee a s\u00ed mismo. Arturo\u00a0Graf Efem\u00e9rides\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0Abril es el cuarto mes del a\u00f1o en el Calendario Gregoriano y tiene 30 d\u00edas.<\/p>\n","protected":false},"author":3,"featured_media":1312,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":{"0":"post-1292","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-efemerides"},"_links":{"self":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts\/1292","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/comments?post=1292"}],"version-history":[{"count":0,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts\/1292\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/media\/1312"}],"wp:attachment":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/media?parent=1292"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/categories?post=1292"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/tags?post=1292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}