{"id":1324,"date":"2009-04-21T00:07:29","date_gmt":"2009-04-21T04:37:29","guid":{"rendered":"http:\/\/www.elpulsodeltiempo.com\/timepulse\/?p=1324"},"modified":"2009-04-21T00:07:29","modified_gmt":"2009-04-21T04:37:29","slug":"sabia-usted-pronostico-2457","status":"publish","type":"post","link":"https:\/\/moonmentum.com\/blog\/uncategorized\/sabia-usted-pronostico-2457\/","title":{"rendered":"Sab\u00eda Usted \/ Pron\u00f3stico # 2457"},"content":{"rendered":"<p style=\"text-align: center;\"><strong><a href=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2009\/04\/fc9072cda4e6c30445e0dd7d9dde4450.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1356  aligncenter lazyload\" style=\"--smush-placeholder-width: 100px; --smush-placeholder-aspect-ratio: 100\/132;border: 0px;\" title=\"max-weber\" data-src=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2009\/04\/fc9072cda4e6c30445e0dd7d9dde4450.jpg\" alt=\"max-weber\" width=\"100\" height=\"132\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><noscript><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1356  aligncenter\" style=\"border: 0px;\" title=\"max-weber\" src=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2009\/04\/fc9072cda4e6c30445e0dd7d9dde4450.jpg\" alt=\"max-weber\" width=\"100\" height=\"132\" \/><\/noscript><\/a><\/strong><\/p>\n<p align=\"center\"><span style=\"color: #888888;\">Max Weber. Pol\u00edtico, economista y soci\u00f3logo alem\u00e1n.<\/span><\/p>\n<p style=\"text-align: justify;\"><strong>En un d\u00eda como hoy naci\u00f3 Max Weber<\/strong>, economista, pol\u00edtico y soci\u00f3logo alem\u00e1n. Su obra m\u00e1s reconocida es el ensayo La \u00e9tica protestante y el esp\u00edritu del capitalismo, que fue el inicio de un trabajo sobre la sociolog\u00eda de la religi\u00f3n. <!--more--><\/p>\n<p style=\"text-align: justify;\"><strong><\/strong>\u00a0<strong>Weber<\/strong> argument\u00f3 que la religi\u00f3n fue uno de los aspectos m\u00e1s importantes que influyeron en las diferencias en el desarrollo de las culturas occidental y oriental. En otra de sus obras famosas, La pol\u00edtica como vocaci\u00f3n<strong>, Weber defini\u00f3 el <\/strong><strong>Estado<\/strong><strong> como una entidad que posee un monopolio en el uso leg\u00edtimo de la fuerza<\/strong>, una definici\u00f3n que fue fundamental en el estudio de la ciencia pol\u00edtica moderna en Occidente. <strong>Su teor\u00eda fue ampliamente conocida a posteriori como la <\/strong><strong>Tesis de Weber<\/strong><strong>.<\/strong> Fue un ni\u00f1o precoz. El regalo de Navidad que le hizo a sus padres en 1876, cuando contaba con trece a\u00f1os, result\u00f3 ser un par de ensayos hist\u00f3ricos, titulados \u00abSobre la maldici\u00f3n de la historia alemana, con referencias especiales a la posici\u00f3n del emperador y el papa\u00bb y \u00abSobre el per\u00edodo del Imperio romano desde Constantino a la migraci\u00f3n de las naciones\u00bb. Parec\u00eda claro entonces que Weber se dedicar\u00eda a las ciencias sociales. A la edad de catorce a\u00f1os escribi\u00f3 cartas llenas de referencias a Homero, Virgilio, Cicer\u00f3n y Livy, y antes de ingresar a la universidad ya pose\u00eda un extenso conocimiento sobre Goethe, Spinoza, Kant y Schopenhauer .<strong>Se incorpor\u00f3 a la fraternidad de su padre<\/strong> y escogi\u00f3 el campo de las leyes al igual que \u00e9l. El ensayo de Weber, La \u00c9tica Protestante y el Esp\u00edritu del Capitalismo, es su obra m\u00e1s conocida. Se dice que este trabajo no deber\u00eda ser visto como un estudio detallado del protestantismo, sino como una introducci\u00f3n a obras posteriores de Weber, en especial a sus estudios de la interacci\u00f3n entre varias ideolog\u00edas religiosas y comportamientos econ\u00f3micos. Junto a Karl Marx, Vilfredo Pareto, Ferdinand T\u00f6nnies y \u00c9mile Durkheim, Max Weber fue uno de los fundadores de la sociolog\u00eda moderna. Mientras Pareto y Durkheim trabajaron en la tradici\u00f3n positivista siguiendo los postulados de Auguste Comte, Weber cre\u00f3 y trabaj\u00f3 en una tradici\u00f3n antipositivista, idealista <strong>y <\/strong><strong>hermen\u00e9utica<\/strong>, al igual que Werner Sombart, su amigo y para entonces, el m\u00e1s famoso representante de la sociolog\u00eda alemana. Estos trabajos iniciaron la revoluci\u00f3n antipositivista de las ciencias sociales, que marc\u00f3 la diferencia entre \u00e9stas y las ciencias naturales, especialmente debido a las acciones sociales de los hombres. Los primeros trabajos de Weber estaban relacionados con la sociolog\u00eda industrial, pero son m\u00e1s conocidos sus \u00faltimos trabajos sobre sociolog\u00eda de la religi\u00f3n y sociolog\u00eda del gobierno.<\/p>\n<p style=\"text-align: justify;\"><a title=\"Max Weber\" href=\"http:\/\/es.wikipedia.org\/wiki\/Max_Weber\" target=\"_blank\"><strong>Max Weber<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Max Weber. Pol\u00edtico, economista y soci\u00f3logo alem\u00e1n. En un d\u00eda como hoy naci\u00f3 Max Weber, economista, pol\u00edtico y soci\u00f3logo alem\u00e1n. Su obra m\u00e1s reconocida es el ensayo La \u00e9tica protestante y el esp\u00edritu del capitalismo, que fue el inicio de un trabajo sobre la sociolog\u00eda de la religi\u00f3n.<\/p>\n","protected":false},"author":3,"featured_media":1356,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-1324","post","type-post","status-publish","format-standard","has-post-thumbnail"],"_links":{"self":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts\/1324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/comments?post=1324"}],"version-history":[{"count":0,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts\/1324\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/media\/1356"}],"wp:attachment":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/media?parent=1324"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/categories?post=1324"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/tags?post=1324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}