{"id":1327,"date":"2009-04-21T00:08:52","date_gmt":"2009-04-21T04:38:52","guid":{"rendered":"http:\/\/www.elpulsodeltiempo.com\/timepulse\/?p=1327"},"modified":"2013-06-03T15:40:09","modified_gmt":"2013-06-03T20:10:09","slug":"efemerides-pronostico-2457","status":"publish","type":"post","link":"https:\/\/moonmentum.com\/blog\/efemerides\/efemerides-pronostico-2457\/","title":{"rendered":"Efem\u00e9rides \/ Pron\u00f3stico # 2457"},"content":{"rendered":"<p style=\"text-align: center;\" align=\"center\"><strong>\u00abSentido de Pertenencia\u00bb<\/strong><\/p>\n<p align=\"center\">El verdadero buscador crece y aprende, y descubre que siempre<br \/>\nes el principal responsable de lo que sucede.<\/p>\n<p align=\"center\"><strong><em>Jorge Bucay<\/em><\/strong><\/p>\n<p align=\"center\"><strong><em><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1361 lazyload\" style=\"--smush-placeholder-width: 120px; --smush-placeholder-aspect-ratio: 120\/151;border: 0px;\" title=\"jorge-bucay\" data-src=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2009\/04\/be89c1a76e7f7367d5c9d686986413d9.jpg\" alt=\"jorge-bucay\" width=\"120\" height=\"151\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><noscript><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1361\" style=\"border: 0px;\" title=\"jorge-bucay\" src=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2009\/04\/be89c1a76e7f7367d5c9d686986413d9.jpg\" alt=\"jorge-bucay\" width=\"120\" height=\"151\" \/><\/noscript><\/em><\/strong><\/p>\n<p style=\"TEXT-ALIGN: justify\"><strong><span style=\"font-size: small;\">Efem\u00e9rides\u00a0\u00a0\u00a0\u00a0<\/span>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Abril<\/strong> es el cuarto mes del a\u00f1o en el Calendario Gregoriano y tiene 30 d\u00edas. Los antiguos romanos le llamaban Aprilis en lat\u00edn.\u00a0<!--more--><\/p>\n<p style=\"text-align: justify;\"><strong>Abril:<\/strong>\u00a0 Del lat\u00edn \u00abaperire\u00bb que significa abrir. Durante este mes se abren las flores y estalla la primavera. Hay historiadores que creen que puede estar dedicado tambi\u00e9n a \u00abaper\u00bb un jabal\u00ed que era venerado por los romanos o que su ra\u00edz etimol\u00f3gica provenga de \u00abaparas\u00bb, una palabra oriental que significa \u00absiguiente\u00bb, o sea, siguiente al primer mes, ya que para los romanos, este era el segundo mes del a\u00f1o.<\/p>\n<p style=\"text-align: justify;\">El <strong>21 de abril<\/strong> es el 111\u00ba d\u00eda del a\u00f1o del Calendario Gregoriano y el 112\u00ba en los a\u00f1os bisiestos. Quedan 254 d\u00edas para finalizar el a\u00f1o.<\/p>\n<p><strong>Acontecimientos:<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>753 adC &#8211;<\/strong> Fecha tradicional de la fundaci\u00f3n de Roma . R\u00f3mulo funda la ciudad con la oposici\u00f3n de su hermano Remo, al que asesina.<br \/>\n<strong>1509<\/strong> &#8211; Enrique VIII asciende al trono de Inglaterra a la muerte de su padre, Enrique VII.<br \/>\n<strong>1831<\/strong> &#8211; Fundaci\u00f3n de Ovalle, ciudad capital de la Provincia de Limar\u00ed, Chile.<br \/>\n<strong>1863<\/strong> &#8211; Bah\u00e1&#8217;u&#8217;ll\u00e1h anuncia p\u00fablicamente Su misi\u00f3n en el jard\u00edn de Ridv\u00e1n, Bagdad, conocido con el sobrenombre de <em>Bah\u00e1&#8217;u&#8217;ll\u00e1h<\/em>, fue un religioso de Oriente Medio fundador de la Fe Bah\u00e1&#8217;\u00ed, donde es considerado un profeta.<br \/>\n<strong>1914<\/strong> &#8211; 2a.Invasi\u00f3n de los Estados Unidos a M\u00e9xico, desembarcando en el puerto de Veracruz.<br \/>\n<strong>1960<\/strong> &#8211; Fundaci\u00f3n de Brasilia, capital administrativa de Brasil.<\/p>\n<p><strong>Nacimientos:<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>1671 &#8211;<\/strong> John Law, fue un economista escoc\u00e9s inventor del papel moneda. Su idea econ\u00f3mica era que el dinero es un medio de intercambio y no constituye una riqueza en s\u00ed mismo. La riqueza nacional depende del comercio. Es el padre de las finanzas y del uso del papel-moneda en lugar del metal y de las facturas.<br \/>\n<strong>1837<\/strong> &#8211; Fredrik Bajer, escritor y pacifista dan\u00e9s, premio Nobel de la Paz en 1908.<br \/>\n<strong>1864<\/strong> &#8211; Max Weber, economista, pol\u00edtico y soci\u00f3logo alem\u00e1n. Su obra m\u00e1s reconocida es el ensayo <em>La \u00e9tica protestante y el esp\u00edritu del capitalismo<\/em>, que fue el inicio de un trabajo sobre la sociolog\u00eda de la religi\u00f3n.<br \/>\n<strong>1889<\/strong>: Paul Karrer, qu\u00edmico suizo, premio Nobel de Qu\u00edmica en 1937. Public\u00f3 muchos trabajos y recibi\u00f3 muchos honores adem\u00e1s del premio Nobel. Su libro de texto <em>Lehrbuch der Organaischen Chemie<\/em> (Libro de texto de Qu\u00edmica Org\u00e1nica) fue publicado en 1927 y ha alcanzado las treinta ediciones en siete idiomas diferentes.<br \/>\n<strong>1926<\/strong> &#8211; Isabel II, reina de Gran Breta\u00f1a.<\/p>\n<p><strong>Fallecimientos:<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>1109<\/strong> &#8211; Anselmo de Canterbury, arzobispo de Canterbury y te\u00f3logo escol\u00e1stico.<br \/>\n<strong>1142<\/strong> &#8211; Pierre Abelard, fil\u00f3sofo y escritor franc\u00e9s. Genio l\u00f3gico y cr\u00edtico indomable, considerado como el mejor en l\u00f3gica de su \u00e9poca y tal vez el pensador m\u00e1s profundo y original sobre el lenguaje y la l\u00f3gica de toda la Edad Media. Conocido por su relaci\u00f3n amorosa con Elo\u00edsa, ser\u00eda castigado con la castraci\u00f3n. \u00ab<em>Cartas a Abelardo\u00bb<\/em> es uno de los textos literarios m\u00e1s le\u00eddos de todos los tiempos.<br \/>\n<strong>1731<\/strong> &#8211; Daniel Defoe, fue un escritor, periodista y esp\u00eda ingl\u00e9s, famoso por su novela <em>Robinson Crusoe.<\/em><\/p>\n<p><strong>Fiestas:<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>* Conmemoraci\u00f3n de la <strong>Fundaci\u00f3n<\/strong><\/strong><strong><span style=\"text-decoration: underline;\"> de Roma<\/span><\/strong> . La fundaci\u00f3n de Roma es referida por varias leyendas, las cuales en tiempos recientes han empezado a ser suplidas por reconstrucciones m\u00e1s cient\u00edficas. <em>La Eneida<\/em> de Virgilio, es una importante fuente de informaci\u00f3n sobre las versiones \u00aboficiales\u00bb de algunos sucesos hist\u00f3ricos de aquel tiempo. <strong>La leyenda<\/strong> del origen de Roma hubiera sido m\u00e1s pobre si los dioses no hubieran tomado parte. Marte (el cual ser\u00e1 uno de los dioses m\u00e1s importantes para Roma) tuvo dos hijos con Rea Silvia. (El nombre Rea Silvia sugiere una deidad menor, una semidiosa de los bosques. Silva significa \u00e1rboles o bosque, y Rea puede estar relacionado con <em>res<\/em> y <em>regnum<\/em>). <strong>Roma arde<\/strong>. Amulio mand\u00f3 a un siervo a matar a los reci\u00e9n nacidos gemelos. Pero el siervo, los puso en una bolsa que dej\u00f3 en el T\u00edber, para que fuesen arrastrados. Los gemelos fueron transportados por el r\u00edo y arribaron a las orillas de un lugar que, curiosamente, las leyendas no especifican. Aqu\u00ed fueron salvados por una loba, que los amamant\u00f3. Esta loba, <em>Luperca<\/em>, a\u00fan es uno de los principales s\u00edmbolos romanos.Y la leyenda dice: El pr\u00edncipe Eneas, despu\u00e9s de la ca\u00edda de Troya, desembarc\u00f3 en las costas italianas. Sus descendientes lejanos, los gemelos R\u00f3mulo y Remo fueron arrojados al r\u00edo T\u00edber en una canastilla. Encontrados por una loba que los adopta y los amamanta, al poco tiempo unos campesinos los encuentran y adoptan, una vez adultos los gemelos fundaron una ciudad donde la loba los salv\u00f3 pero despu\u00e9s de una disputa por el poder, R\u00f3mulo mata a Remo y queda como el jefe absoluto nombr\u00e1ndola Roma.<\/p>\n<p style=\"TEXT-ALIGN: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-1365 lazyload\" title=\"romulo-y-remo3\" data-src=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2009\/04\/romulo-y-remo3-300x225.jpg\" alt=\"romulo-y-remo3\" width=\"175\" height=\"131\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 175px; --smush-placeholder-aspect-ratio: 175\/131;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-1365\" title=\"romulo-y-remo3\" src=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2009\/04\/romulo-y-remo3-300x225.jpg\" alt=\"romulo-y-remo3\" width=\"175\" height=\"131\" \/><\/noscript><span style=\"color: #888888;\">Luperca amamantando a los gemelos R\u00f3mulo y Remo,<br \/>\nla leyenda m\u00e1s difundida acerca de la fundaci\u00f3n de Roma.\u00a0<\/span><\/p>\n<p style=\"TEXT-ALIGN: justify\">Sobre el monte Capitolino, a mediod\u00eda, el 21 de abril de cada a\u00f1o, una campana especial llamada la <em>patarina<\/em> suena del Campidoglio para conmemorar la fundaci\u00f3n de Roma. En esa ocasi\u00f3n, el famoso ca\u00f1\u00f3n de Gianicolo permanece silencioso, el \u00fanico d\u00eda del a\u00f1o en que no suena.<\/p>\n<p><a title=\"R\u00f3mulo y Remo\" href=\"http:\/\/es.wikipedia.org\/wiki\/R%C3%B3mulo_y_Remo\">R\u00f3mulo y Remo<\/a>\u00a0<\/p>\n<p><strong>* D\u00eda Sagrado del calendario Bad\u00ed.<\/strong>\u00a0 Primer d\u00eda del Festival de Ridv\u00e1n (21 abril &#8211; 2 mayo) en conmemoraci\u00f3n del anuncio de Bah\u00e1&#8217;u&#8217;ll\u00e1h<\/p>\n<p>\u00a0<\/p>\n<p style=\"TEXT-ALIGN: justify\">\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abSentido de Pertenencia\u00bb El verdadero buscador crece y aprende, y descubre que siempre es el principal responsable de lo que sucede. Jorge Bucay Efem\u00e9rides\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Abril es el cuarto mes del a\u00f1o en el Calendario Gregoriano y tiene 30 d\u00edas. Los antiguos romanos le llamaban Aprilis en lat\u00edn.\u00a0<\/p>\n","protected":false},"author":3,"featured_media":1361,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":{"0":"post-1327","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-efemerides"},"_links":{"self":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts\/1327","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/comments?post=1327"}],"version-history":[{"count":0,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts\/1327\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/media\/1361"}],"wp:attachment":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/media?parent=1327"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/categories?post=1327"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/tags?post=1327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}