	<style type="text/css">
		.postTabs_divs{
	padding: 4px;	
}


.postTabs_titles{
	display:none;	
}

ul.postTabs
	{
	margin:0px 0px 1em !important;
	padding: 0.2em 1em 0.2em 20px !important;
	border-bottom: 1px solid #ccc !important;
	font-size: 14px;
	list-style-type: none !important;
	line-height:normal;
	text-align: left;
	display: block !important;
	background: none;
	}

ul.postTabs li
	{	
	display: inline !important;
	font-size: 14px;
	line-height:normal;
	background: none;
	padding: 0px;
	margin: 0px;
	}
  
ul.postTabs li:before{
content: none;	
}  
  	
ul.postTabs li a
	{
	text-decoration: none;
	background: #808080;
	border: 1px solid #ccc  !important;
	padding: 0.2em 0.4em !important;
	color: #ffffff !important;
	outline:none;	
	cursor: pointer;
	
	}
	
ul.postTabs li.postTabs_curr a{
	border-bottom: 1px solid #fff  !important;
	background: #fff;
	color: #000000 !important;
	text-decoration: none;
	
	}

ul.postTabs li a:hover
	{
	color: #666 !important;
	background: #d4d4d4;
	text-decoration: none;
	
	}

.postTabsNavigation{
	display: block !important;
	overflow:hidden;
}

.postTabs_nav_next{
	float:right;
}

.postTabs_nav_prev{
	float:left;
}

@media screen and (max-width: 699px) {
	ul.postTabs li {
		display: block !important;
		width: 100%;
		margin: -3px;
	}
	ul.postTabs li a {
		display: block;
		width: 96%;
	}
}	</style>
	{"id":142549,"date":"2013-04-09T00:10:31","date_gmt":"2013-04-09T04:40:31","guid":{"rendered":"http:\/\/www.moonmentum.com\/blog\/?p=142549"},"modified":"2013-05-09T09:15:20","modified_gmt":"2013-05-09T13:45:20","slug":"domenico-dragonetti","status":"publish","type":"post","link":"https:\/\/moonmentum.com\/blog\/archivo\/multimedia\/domenico-dragonetti\/","title":{"rendered":"Domenico Dragonetti"},"content":{"rendered":"<div class=\"mceTemp\">\n<div class=\"mceTemp\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-147484 lazyload\" style=\"--smush-placeholder-width: 192px; --smush-placeholder-aspect-ratio: 192\/250;float: right; margin: 6px; border: 0px;\" title=\"Domenico-Dragonetti2\" data-src=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2013\/04\/Domenico-Dragonetti2-230x300.png\" alt=\"Domenico-Dragonetti2\" width=\"192\" height=\"250\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><noscript><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-147484\" style=\"float: right; margin: 6px; border: 0px;\" title=\"Domenico-Dragonetti2\" src=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2013\/04\/Domenico-Dragonetti2-230x300.png\" alt=\"Domenico-Dragonetti2\" width=\"192\" height=\"250\" \/><\/noscript>Nacido en Venecia,\u00a0Italia\u00a0en 1763, a Domenico Dragonetti se le reconoce como m\u00fasico de cuerdas y uno de los primeros contrabajistas en ser aclamado internacionalmente. Un hombre descrito como alto y delgado, mas\u00a0all\u00e1\u00a0del promedio de un italiano. Su m\u00fasica asombr\u00f3 e inspir\u00f3 a Beethoven.<\/div>\n<\/div>\n<p>Fue el contrabajista m\u00e1s grande de Europa y posiblemente \u00fanico virtuoso de su\u00a0\u00e9poca. Realiz\u00f3 principalmente giras en el extranjero realizando el repertorio limitado existente para el contrabajo.<\/p>\n<p>Se inici\u00f3 tocando la guitarra, el viol\u00edn y el contrabajo desde una edad muy temprana.\u00a0A los 13 a\u00f1os ya era el primer contrabajista de la \u00d3pera bufa de Venecia. Uno de sus maestros fue\u00a0Berini quien era el principal contrabajista en la Capilla de San Marcos, Venecia.<\/p>\n<p>Su contrabajo fue hecho especialmente para \u00e9l, era de extra-alto, con tres cuerdas en lugar de cuatro. Cuelga hoy en el Museo Victoria y Alberto de Londres.<!--more--><\/p>\n<p>Su extraordinaria t\u00e9cnica de agarre y uso del arco (que puede apreciarse en el retrato y el\u00a0daguerrotipo\u00a0que aparecen como\u00a0im\u00e1genes\u00a0anexas), le permito desempe\u00f1arse con una habilidad tal que fue considerado un virtuoso de doble bajo (o contrabajo) en la\u00a0m\u00fasica\u00a0cl\u00e1sica\u00a0y es hoy admirado por bajistas de jazz y otros\u00a0g\u00e9neros, quiz\u00e1 el primer virtuoso de este instrumento.<\/p>\n<p>Gracias a esta t\u00e9cnica desarroll\u00f3 un \u201cstaccato percussivo\u201d, este m\u00e9todo novedoso, desconocido hasta entonces, le permiti\u00f3 desarrollar conciertos y composiciones innovadoras para su tiempo.<\/p>\n<p>Colabor\u00f3 entre otros con Mendelssohn, Liszt, Rossini y Paganini. Tambi\u00e9n fue considerado un virtuoso en la ejecuci\u00f3n del viol\u00edn.<\/p>\n<p>Dragonetti obtuvo muchos bajos finos durante su vida y dej\u00f3 a la mayor\u00eda de ellos a sus amigos en su testamento. Su bajo m\u00e1s famoso, un Gasparo da Salo le\u00a0fue\u00a0obsequiado a \u00e9l por las monjas benedictinas del convento de San Pedro en Vicenza. A su muerte, fue devuelto a la Capilla de San Marco en Venecia, donde \u00e9l toco en el principio de su carrera.<\/p>\n<p><ul id='postTabs_ul_142549' class='postTabs' style='display:none'>\n<li id='postTabs_li_0_142549' class='postTabs_curr'><a  id=\"142549_0\" onMouseOver=\"posTabsShowLinks('Nonnoliu &#8211; Doublebass concerto 1st mvt.'); return true;\"  onMouseOut=\"posTabsShowLinks();\"  class='postTabsLinks'>Nonnoliu &#8211; Doublebass concerto 1st mvt.<\/a><\/li>\n<li id='postTabs_li_1_142549' ><a  id=\"142549_1\" onMouseOver=\"posTabsShowLinks('GARY KARR'); return true;\"  onMouseOut=\"posTabsShowLinks();\"  class='postTabsLinks'>GARY KARR<\/a><\/li>\n<li id='postTabs_li_2_142549' ><a  id=\"142549_2\" onMouseOver=\"posTabsShowLinks('Chang chin shan played \u00abDragonetti Nr3 Allegro\u00bbAge12'); return true;\"  onMouseOut=\"posTabsShowLinks();\"  class='postTabsLinks'>Chang chin shan played \u00abDragonetti Nr3 Allegro\u00bbAge12<\/a><\/li>\n<li id='postTabs_li_3_142549' ><a  id=\"142549_3\" onMouseOver=\"posTabsShowLinks('Double Bass concerto in A Major MOV I'); return true;\"  onMouseOut=\"posTabsShowLinks();\"  class='postTabsLinks'>Double Bass concerto in A Major MOV I<\/a><\/li>\n<li id='postTabs_li_4_142549' ><a  id=\"142549_4\" onMouseOver=\"posTabsShowLinks('Double Bass concerto in A Major MOV II'); return true;\"  onMouseOut=\"posTabsShowLinks();\"  class='postTabsLinks'>Double Bass concerto in A Major MOV II<\/a><\/li>\n<li id='postTabs_li_5_142549' ><a  id=\"142549_5\" onMouseOver=\"posTabsShowLinks('Double Bass concerto in A Major MOV III'); return true;\"  onMouseOut=\"posTabsShowLinks();\"  class='postTabsLinks'>Double Bass concerto in A Major MOV III<\/a><\/li>\n<\/ul>\n\n<div class='postTabs_divs postTabs_curr_div' id='postTabs_0_142549'>\n<span class='postTabs_titles'><b>Nonnoliu &#8211; Doublebass concerto 1st mvt.<\/b><\/span><\/p>\n<p style=\"text-align: center;\"><object classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" width=\"500\" height=\"405\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"allowscriptaccess\" value=\"always\" \/><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/4QWfJTLbej8?fs=1&amp;hl=en_US&amp;rel=0\" \/><param name=\"allowfullscreen\" value=\"true\" \/><embed type=\"application\/x-shockwave-flash\" width=\"500\" height=\"405\" src=\"http:\/\/www.youtube.com\/v\/4QWfJTLbej8?fs=1&amp;hl=en_US&amp;rel=0\" allowfullscreen=\"true\" allowscriptaccess=\"always\"><\/embed><\/object><\/p>\n<p><\/div>\n\n<div class='postTabs_divs' id='postTabs_1_142549'>\n<span class='postTabs_titles'><b>GARY KARR<\/b><\/span><\/p>\n<p style=\"text-align: center;\"><object classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" width=\"500\" height=\"405\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"allowscriptaccess\" value=\"always\" \/><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/b3nUT3kUKLY?fs=1&amp;hl=en_US&amp;rel=0\" \/><param name=\"allowfullscreen\" value=\"true\" \/><embed type=\"application\/x-shockwave-flash\" width=\"500\" height=\"405\" src=\"http:\/\/www.youtube.com\/v\/b3nUT3kUKLY?fs=1&amp;hl=en_US&amp;rel=0\" allowfullscreen=\"true\" allowscriptaccess=\"always\"><\/embed><\/object><\/p>\n<p><\/div>\n\n<div class='postTabs_divs' id='postTabs_2_142549'>\n<span class='postTabs_titles'><b>Chang chin shan played \u00abDragonetti Nr3 Allegro\u00bbAge12<\/b><\/span><\/p>\n<p style=\"text-align: center;\"><object classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" width=\"500\" height=\"405\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"allowscriptaccess\" value=\"always\" \/><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/mS6TXrnCZM0?fs=1&amp;hl=en_US&amp;rel=0\" \/><param name=\"allowfullscreen\" value=\"true\" \/><embed type=\"application\/x-shockwave-flash\" width=\"500\" height=\"405\" src=\"http:\/\/www.youtube.com\/v\/mS6TXrnCZM0?fs=1&amp;hl=en_US&amp;rel=0\" allowfullscreen=\"true\" allowscriptaccess=\"always\"><\/embed><\/object><\/p>\n<p><\/div>\n\n<div class='postTabs_divs' id='postTabs_3_142549'>\n<span class='postTabs_titles'><b>Double Bass concerto in A Major MOV I<\/b><\/span><\/p>\n<p style=\"text-align: center;\"><object classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" width=\"500\" height=\"311\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"allowscriptaccess\" value=\"always\" \/><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/n3rlfp7oiQk?fs=1&amp;hl=en_US&amp;rel=0\" \/><param name=\"allowfullscreen\" value=\"true\" \/><embed type=\"application\/x-shockwave-flash\" width=\"500\" height=\"311\" src=\"http:\/\/www.youtube.com\/v\/n3rlfp7oiQk?fs=1&amp;hl=en_US&amp;rel=0\" allowfullscreen=\"true\" allowscriptaccess=\"always\"><\/embed><\/object><\/p>\n<p><\/div>\n\n<div class='postTabs_divs' id='postTabs_4_142549'>\n<span class='postTabs_titles'><b>Double Bass concerto in A Major MOV II<\/b><\/span><\/p>\n<p style=\"text-align: center;\"><object classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" width=\"500\" height=\"311\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"allowscriptaccess\" value=\"always\" \/><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/j8kuoBvQLR0?fs=1&amp;hl=en_US&amp;rel=0\" \/><param name=\"allowfullscreen\" value=\"true\" \/><embed type=\"application\/x-shockwave-flash\" width=\"500\" height=\"311\" src=\"http:\/\/www.youtube.com\/v\/j8kuoBvQLR0?fs=1&amp;hl=en_US&amp;rel=0\" allowfullscreen=\"true\" allowscriptaccess=\"always\"><\/embed><\/object><\/p>\n<p><\/div>\n\n<div class='postTabs_divs' id='postTabs_5_142549'>\n<span class='postTabs_titles'><b>Double Bass concerto in A Major MOV III<\/b><\/span><\/p>\n<p style=\"text-align: center;\"><object classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" width=\"500\" height=\"311\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"allowscriptaccess\" value=\"always\" \/><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/IUES9mYneQE?fs=1&amp;hl=en_US&amp;rel=0\" \/><param name=\"allowfullscreen\" value=\"true\" \/><embed type=\"application\/x-shockwave-flash\" width=\"500\" height=\"311\" src=\"http:\/\/www.youtube.com\/v\/IUES9mYneQE?fs=1&amp;hl=en_US&amp;rel=0\" allowfullscreen=\"true\" allowscriptaccess=\"always\"><\/embed><\/object><\/p>\n<p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Este 2013 se conmemora el 250 aniversario del natalicio de Domenico Dragonetti, a quien se le reconoce como uno de los primeros contrabajistas en ser aclamado internacionalmente. <a href=\"http:\/\/www.moonmentum.com\/blog\/?p=142549\">Ver m\u00e1s\u2026<\/a><\/p>\n","protected":false},"author":6,"featured_media":142578,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8198],"tags":[8433,9566,9564,9563,381,6663,9565,739],"class_list":{"0":"post-142549","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-multimedia","8":"tag-arco","9":"tag-composiciones","10":"tag-contrabajo","11":"tag-cuerdas","12":"tag-musica","13":"tag-musico","14":"tag-staccato-percussivo","15":"tag-violin"},"_links":{"self":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts\/142549","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/comments?post=142549"}],"version-history":[{"count":0,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts\/142549\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/media\/142578"}],"wp:attachment":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/media?parent=142549"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/categories?post=142549"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/tags?post=142549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}