{"id":192869,"date":"2015-05-26T10:04:14","date_gmt":"2015-05-26T14:34:14","guid":{"rendered":"http:\/\/moonmentum.com\/blog\/?p=192869"},"modified":"2015-05-26T10:05:53","modified_gmt":"2015-05-26T14:35:53","slug":"ofiuco-el-cargador-de-serpientes","status":"publish","type":"post","link":"https:\/\/moonmentum.com\/blog\/actualidad\/observatorio-moonmentum\/ofiuco-el-cargador-de-serpientes\/","title":{"rendered":"Ofiuco, el cargador de serpientes"},"content":{"rendered":"<p>Ofiuco u Ophiuchus (el portador de la serpiente o Serpentario) es una de las 88 constelaciones modernas, y era una de las 48 listadas por Ptolomeo. Puede verse en ambos hemisferios entre los meses de abril a octubre por estar situada sobre el ecuador celeste y aunque las estrellas brillen tenuemente, la forma de tetera de Ofiuco hace que sea f\u00e1cil de encontrar.<\/p>\n<p>La constelaci\u00f3n es una combinaci\u00f3n de tres figuras diferentes. Ofiuco est\u00e1 sosteniendo la serpiente Caput en su mano izquierda y la serpiente Cauda en su mano derecha. Se encuentra al sur de H\u00e9rcules y al norte del Escorpi\u00f3n.<\/p>\n<p>En la mitolog\u00eda griega, Ofiuco representa Asclepio, el dios de la medicina. Asclepio era el hijo de Apolo, y fue educado por Chir\u00f3n el centauro. Asclepio aprendi\u00f3 c\u00f3mo hacer que las personas muertas regresaran a la vida, lo cual preocup\u00f3 mucho a Hades. El dios del submundo pidi\u00f3 a su hermano Zeus, que matara al dios de la medicina. Zeus lo mat\u00f3, pero para honrarlo, puso la figura de Asclepio en el cielo.<\/p>\n<p>En esta constelaci\u00f3n no hay muchas estrellas brillantes, pero hay una que es bastante \u00fanica. RS Ophiuchi es un tipo de estrella llamada nova recurrente. Estos raros objetos permanecen opacas por largos per\u00edodos de tiempo y de pronto, vuelven a brillar. A la estrella m\u00e1s brillante se le conoce como, Ras Alhague, y es la cabeza del portador de serpientes.<\/p>\n<p>Ophiuchi est\u00e1 lleno de objetos celestiales. En la constelaci\u00f3n hay numerosos racimos y una nebulosa.<\/p>\n<p><strong>25 de Mayo, 2015<\/strong><\/p>\n<ul>\n<li>La Luna est\u00e1 en su primer cuarto a las 1:20 p.m.(EDT). En ese momento, la luz solar ilumina una mitad del hemisferio lunar que nos da la cara a la Tierra. La Luna asciende temprano por la tarde y se encuentra alta en el suroeste al caer la noche.<\/li>\n<\/ul>\n<p><strong>26 de Mayo, 2015<\/strong><\/p>\n<ul>\n<li>Como 160 c\u00famulos globulares orbitan al centro de la galaxia la V\u00eda L\u00e1ctea. El m\u00e1s grande y brillante es Omega Centauri, el cual est\u00e1 bajo en el sur temprano por la noche. Quiz\u00e1 sea el n\u00facleo desnudo de una galaxia m\u00e1s peque\u00f1a que en alg\u00fan tiempo la V\u00eda L\u00e1ctea afect\u00f3.<\/li>\n<li>Luna en el apogeo. (Distancia geoc\u00e9ntrica: 404244 Km | Iluminaci\u00f3n: 61.4%)<\/li>\n<\/ul>\n<p><strong>27 de Mayo, 2015<\/strong><\/p>\n<ul>\n<li>Algunas de las luces brillantes del invierno se est\u00e1n saliendo del cielo. Bajo en el oeste al caer la noche, busque a Proci\u00f3n en Canes Menor, el peque\u00f1o can. Y observe hacia su derecha superior para encontrar a los gemelos de G\u00e9minis arriba de Venus, la \u00abestrella vespertina\u00bb.<\/li>\n<li>Mercurio a 1.69\u00b0S de Marte. (Elongaci\u00f3n de Mercurio: 4.8\u00b0)<\/li>\n<\/ul>\n<p><strong>28 de Mayo, 2015<\/strong><\/p>\n<ul>\n<li>Corona Boreales, la cruz del norte, se encuentra a la mitad del cielo oriental hoy al caer la noche. Es un peque\u00f1o semic\u00edrculo de estrellas moderadamente brillantes que se abre hacia la izquierda. Est\u00e1 coronado por un sistema estelar binario conocido como Alphecca.<\/li>\n<\/ul>\n<p><strong>29 de Mayo, 2015<\/strong><\/p>\n<ul>\n<li>Espica est\u00e1 cerca de la Luna, hacia su derecha, al caer la noche. La estrella m\u00e1s brillante de Virgo resplandece de color azul-blanco, indicando que su superficie es miles de grados m\u00e1s caliente que el Sol<em>.<\/em><\/li>\n<\/ul>\n<p><strong>30 de Mayo, 2015<\/strong><\/p>\n<ul>\n<li>Mercurio en conjunci\u00f3n inferior. (Distancia geoc\u00e9ntrica: 0.54913 U.A.)<\/li>\n<li><strong>Ofiuco, el cargador de serpientes<\/strong>, est\u00e1 en buena vista esta noche. La gran constelaci\u00f3n sube arriba del horizonte como a las 10:00 p.m., y describe un arco alto en el sur durante la noche. La mayor\u00eda de sus estrellas son relativamente d\u00e9biles, as\u00ed que usted necesitar\u00e1 una carta estelar para encontrarlas.<\/li>\n<\/ul>\n<p><strong>31 de Mayo, 2015<\/strong><\/p>\n<ul>\n<li>La gibosa Luna est\u00e1 en \u00abbalance \u00bb esta noche. Est\u00e1 pasando a trav\u00e9s de Libra, la balanza. Las dos estrellas m\u00e1s brillantes de Libra est\u00e1n cerca y arriba de la Luna. El brillante planeta Saturno est\u00e1 ligeramente m\u00e1s alejado y hacia la izquierda inferior de la Luna, con la anaranjada Arturo debajo de Saturno.<\/li>\n<\/ul>\n<p><span style=\"color: #808080;\"><em>\u00bfCu\u00e1ntas veces te detienes a observar lo que el cielo cada noche coloca en cartelera?\u2026 Recuerda el axioma que dice \u201cComo es arriba\u2026 es abajo\u201d\u2026 El cielo y las estrellas no son un adorno\u2026 son una realidad.<\/em><\/span><\/p>\n<p><span style=\"color: #808080;\"><em>Observar nos conecta en un 30% con la energ\u00eda del Universo.<br \/>\nImitar lo observado nos conecta en un 70% con la energ\u00eda del Universo\u2026<br \/>\nEmular lo observado nos convierte en la energ\u00eda.<\/em><\/span><\/p>\n<p><sub><sup><span style=\"color: #808080;\"><strong>Fuentes:<\/strong>\u00a0<\/span><\/sup><sup><span style=\"color: #808080;\">radiouniverso.org,\u00a0, stardate.org, elcielodelmes.com, verelcielo.es, astro.inaoep.mx, saberesyciencias.com<\/span><\/sup><\/sub><\/p>\n<p><sub><sup><span style=\"color: #808080;\"><br \/>\n<\/span><\/sup><\/sub><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ofiuco u Ophiuchus (el portador de la serpiente o Serpentario) es una de las 88 constelaciones modernas, y era una de las 48 listadas por Ptolomeo. Puede verse en ambos hemisferios entre los meses de abril a octubre por estar situada sobre el ecuador celeste y aunque las estrellas brillen tenuemente, la forma de tetera [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":192870,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[593,3514,17170],"class_list":{"0":"post-192869","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-observatorio-moonmentum","8":"tag-luna","9":"tag-ofiuco","10":"tag-ophiuchi"},"_links":{"self":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts\/192869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/comments?post=192869"}],"version-history":[{"count":0,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts\/192869\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/media\/192870"}],"wp:attachment":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/media?parent=192869"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/categories?post=192869"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/tags?post=192869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}