{"id":192966,"date":"2015-06-02T08:24:22","date_gmt":"2015-06-02T12:54:22","guid":{"rendered":"http:\/\/moonmentum.com\/blog\/?p=192966"},"modified":"2015-06-02T10:15:32","modified_gmt":"2015-06-02T14:45:32","slug":"alimentos-felices","status":"publish","type":"post","link":"https:\/\/moonmentum.com\/blog\/actualidad\/cocinando-con-los-dioses\/alimentos-felices\/","title":{"rendered":"Alimentos felices"},"content":{"rendered":"<p>\u201cLa felicidad es como una mariposa. Cuanto m\u00e1s la persigues, m\u00e1s huye. Pero si vuelves la atenci\u00f3n hacia otras cosas, ella viene y suavemente se posa en tu hombro. La felicidad no es una posada en el camino, sino una forma de caminar por la vida.\u201d<\/p>\n<p>Existen dos elementos qu\u00edmicos que influyen en nuestro estado emocional. Se trata de la\u00a0<strong>serotonina<\/strong>\u00a0y la <strong>melatonina<\/strong>\u00a0que hacen la labor en nuestro cerebro para mantenernos de buen humor y con mucho \u00e1nimo.<br \/>\n\u00c9stos los generamos naturalmente, sin embargo s\u00ed hay algunos alimentos que ayudan a que se produzcan con mayor facilidad. Especialmente cuando hemos tenido un mal momento, cuando padecemos de insomnio o cuando estamos en esos d\u00edas del mes en los que nada nos cae bien.<\/p>\n<p>La clave est\u00e1 en que diariamente consumamos alimentos que tengan un amino\u00e1cido llamado\u00a0<strong>tript\u00f3fano <\/strong>para que nuestro cerebro se sienta feliz y para que tengamos buena calidad de sue\u00f1o.<\/p>\n<p>\u00bfD\u00f3nde est\u00e1 este amino\u00e1cido? Las mayores concentraciones las encuentras en los siguientes alimentos:<\/p>\n<p><strong>Nueces, pl\u00e1tano, pi\u00f1a, kiwi, ciruelas, tomate, pavo, leche, yogurt, huevo, pescado y porotos.<\/strong><\/p>\n<p>Alimentos que generan felicidad<\/p>\n<p>\u00bfCu\u00e1ntas veces has escuchado el dicho\u00a0<strong><em>Somos lo que comemos<\/em><\/strong>? Y si es as\u00ed, \u00bfpor qu\u00e9 no a\u00f1adir en nuestra dieta alimentos que provocan felicidad? Puede parecer ut\u00f3pico, pero a estas alturas est\u00e1 comprobado que\u00a0<strong>el cerebro obtiene las herramientas para su funcionamiento a partir de la dieta<\/strong>.<\/p>\n<p>\u00bfCu\u00e1les son esos alimentos que proporcionan la felicidad? La clave est\u00e1 en sus caracter\u00edsticas nutricionales, es decir, por poseer principios activos y nutrientes que influyen en el estado de \u00e1nimo. Es por ejemplo el caso de los alimentos con tript\u00f3fano, un amino\u00e1cido esencial en la nutrici\u00f3n humana que ayuda a promover la liberaci\u00f3n de la serotonina, el neurotransmisor que afecta directamente a nuestro estado de humor y que es conocida como la \u201chormona de la felicidad\u201d.<\/p>\n<p>Igual de importantes son los\u00a0<strong>carbohidratos con fibra<\/strong>, que nos proporcionan vitalidad, las\u00a0<strong>vitaminas B y C<\/strong>, para evitar el cansancio y la debilidad, y el <strong>Omega 3<\/strong>, que ayuda a disminuir la depresi\u00f3n.<\/p>\n<p>A continuaci\u00f3n, una lista de\u00a0<strong>10 alimentos que te ayudan ser feliz<\/strong>:<\/p>\n<ul>\n<li><strong>Pl\u00e1tano:<\/strong>Es un alimento rico en tript\u00f3fano y que, por lo tanto, favorece la producci\u00f3n de serotonina. Adem\u00e1s, tiene un efecto calmante sobre el sistema nervioso y genera energ\u00eda.<\/li>\n<li><strong>Cerezas:<\/strong>Son conocidas como las \u201caspirinas naturales\u201d; incluso investigadores de la Universidad de Michigan han afirmado que comer 20 cerezas al d\u00eda es m\u00e1s efectivo que algunos antidepresivos. Esto es por su alto contenido de antoci\u00e1nicos.<\/li>\n<li><strong>Chocolate:<\/strong>Favorece la absorci\u00f3n de tript\u00f3fano que aumenta el nivel de serotonina. A su vez, contiene cafe\u00edna y az\u00facar que provoca un efecto estimulante para el cerebro.<\/li>\n<li><strong>Pollo:<\/strong>Contiene una importante dosis de selenio, un oliglemento esencial. Unos psic\u00f3logos Brit\u00e1nicos dieron de comer a un grupo de personas 100 mg de selenio y comprobaron que despu\u00e9s los sujetos estaban m\u00e1s contentos.<\/li>\n<li><strong>Pi\u00f1a:<\/strong>Estimula la producci\u00f3n de serotonina, alivia la ansiedad y calma el sistema nervioso.<\/li>\n<li><strong>Pescado azul (salm\u00f3n, at\u00fan, etc):<\/strong>Pescados con alto contenido de Omega-3.<\/li>\n<li><strong>Espinacas:<\/strong>Vegetal muy rico en \u00e1cido f\u00f3lico y vitamina B que favorecen la producci\u00f3n de serotonina.<\/li>\n<li><strong>Garbanzo:<\/strong>Fuente importante de tript\u00f3fano para producir serotonina.<\/li>\n<li><strong>Pimiento:<\/strong>Al igual que el chile y, en general, el picante, contiene capsaicina, una substancia que provoca calor y ardor en el cuerpo que el cerebro percibe como dolor. Para calmarlo, se generan endorfinas que provocan sensaci\u00f3n de bienestar.<\/li>\n<\/ul>\n<p><a href=\"http:\/\/moonmentum.com\/blog\/wp-content\/uploads\/2015\/06\/243c09694bf6f85c0faabe3becf1f7cc.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-192967 size-large lazyload\" data-src=\"http:\/\/moonmentum.com\/blog\/wp-content\/uploads\/2015\/06\/alimentos-de-felicidad-1024x427.jpg\" alt=\"alimentos de felicidad\" width=\"700\" height=\"292\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 700px; --smush-placeholder-aspect-ratio: 700\/292;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-192967 size-large\" src=\"http:\/\/moonmentum.com\/blog\/wp-content\/uploads\/2015\/06\/alimentos-de-felicidad-1024x427.jpg\" alt=\"alimentos de felicidad\" width=\"700\" height=\"292\" \/><\/noscript><\/a><\/p>\n<p><strong>Fuentes:\u00a0<\/strong><a href=\"http:\/\/www.elciudadano.cl\/2015\/03\/20\/153884\/13-alimentos-que-te-ayudan-a-mejorar-el-humor-y-el-animo\/\">elciudadano.cl<\/a>,\u00a0<a href=\"http:\/\/vivirenflow.com\/alimentos-que-generan-felicidad\/\">vivirenflow.com<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>Nota:<\/strong> Bendice tus alimentos no desde la oraci\u00f3n sino desde la sensaci\u00f3n, es decir a trav\u00e9s de los sentidos. Recuerda que al bendecir los alimentos estas elevando su frecuencia!<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cLa felicidad es como una mariposa. Cuanto m\u00e1s la persigues, m\u00e1s huye. Pero si vuelves la atenci\u00f3n hacia otras cosas, ella viene y suavemente se posa en tu hombro. La felicidad no es una posada en el camino, sino una forma de caminar por la vida.\u201d Existen dos elementos qu\u00edmicos que influyen en nuestro estado [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":192970,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":{"0":"post-192966","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-cocinando-con-los-dioses"},"_links":{"self":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts\/192966","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/comments?post=192966"}],"version-history":[{"count":0,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts\/192966\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/media\/192970"}],"wp:attachment":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/media?parent=192966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/categories?post=192966"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/tags?post=192966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}