{"id":20335,"date":"2010-03-13T00:03:39","date_gmt":"2010-03-13T04:33:39","guid":{"rendered":"http:\/\/www.moonmentum.com\/blog\/?p=20335"},"modified":"2013-06-13T10:36:52","modified_gmt":"2013-06-13T15:06:52","slug":"serpens-asciende-en-el-cielo-nocturno","status":"publish","type":"post","link":"https:\/\/moonmentum.com\/blog\/actualidad\/observatorio-moonmentum\/serpens-asciende-en-el-cielo-nocturno\/","title":{"rendered":"Serpens asciende en el cielo nocturno"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-161797 lazyload\" style=\"--smush-placeholder-width: 250px; --smush-placeholder-aspect-ratio: 250\/203;float: left; margin: 6px;\" alt=\"serpens\" data-src=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2010\/03\/90ad1e66a5d6d0773043e6d36266de04.jpg\" width=\"250\" height=\"203\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><noscript><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-161797\" style=\"float: left; margin: 6px;\" alt=\"serpens\" src=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2010\/03\/90ad1e66a5d6d0773043e6d36266de04.jpg\" width=\"250\" height=\"203\" \/><\/noscript>Las mitades divididas de una serpiente se est\u00e1n moviendo hacia el cielo nocturno. Conocida como Serpens, la serpiente, ascienden tarde por la noche. La constelaci\u00f3n est\u00e1 dividida porque la serpiente se enrolla alrededor de las estrellas de Ofiuco, el cargador de serpientes.<\/p>\n<p><strong><span style=\"font-size: medium;\">Ofiuco y Serpens<\/span><\/strong><\/p>\n<p>Dos constelaciones poco apreciadas aparecen en el suroeste esta tarde, encima de la Luna y del brillante planeta J\u00fapiter. Las constelaciones son Ofiuco, el portador de la serpiente, y Serpens, la serpiente.<!--more--><\/p>\n<p>Ofiuco es una de las constelaciones m\u00e1s grandes. Y, lo que es m\u00e1s importante, se encuentra a lo largo de la ecl\u00edptica -la trayectoria del Sol por el cielo. Las constelaciones a lo largo de este trayecto forman el zodiaco. Pero Ofiuco no est\u00e1 incluida en la alineaci\u00f3n, a pesar de que el Sol pasa m\u00e1s tiempo dentro de sus l\u00edmites que en Escorpio, que est\u00e1 al lado.<\/p>\n<p>Ofiuco representa al fundador de la medicina. Seg\u00fan la mitolog\u00eda, ten\u00eda tanta habilidad para curar que pod\u00eda incluso revivir a los muertos. Esto le aproximaba a los poderes de la serpiente, la cual puede matar, pero tambi\u00e9n se renueva anualmente al mudar de piel. Por eso, en el cielo, al m\u00e9dico tambi\u00e9n se le conoce como el portador de la serpiente.<\/p>\n<p>Ofiuco sujeta a Serpens. La cabeza de la serpiente est\u00e1 al oeste de Ofiuco, con la cola al este -cortada por el cuerpo de Ofiuco.<\/p>\n<p>Serpens y Ofiuco est\u00e1n bastante altas en el suroeste al anochecer. Busque a la Luna baja en el cielo, con el brillante J\u00fapiter hacia su parte superior izquierda. Ofiuco y Serpens se extienden por encima de esta brillante pareja.<\/p>\n<p><em>\u00bfCu\u00e1ntas veces usted se detiene a observar lo que el cielo cada noche coloca en cartelera?\u2026 Recuerde el axioma que dice \u201cComo es arriba\u2026es abajo\u201d\u2026 El cielo y las estrellas no son un adorno\u2026 son una realidad.<\/em><\/p>\n<p><strong><em>Observar<\/em><\/strong><em> nos conecta en un 30% con la energ\u00eda del Universo<br \/>\n<strong>Imitar<\/strong> lo observado\u00a0 nos conecta en un 70% con la energ\u00eda del Universo\u2026<br \/>\n<strong>Emular<\/strong> lo observado nos convierte en la energ\u00eda.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las mitades divididas de una serpiente se est\u00e1n moviendo hacia el cielo nocturno. Conocida como Serpens, la serpiente, ascienden tarde por la noche. La constelaci\u00f3n est\u00e1 dividida porque la serpiente se enrolla alrededor de las estrellas de Ofiuco, el cargador de serpientes. Ofiuco y Serpens Dos constelaciones poco apreciadas aparecen en el suroeste esta tarde, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":161797,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[3511,3513,1444,17187,3514,3510,3512],"class_list":{"0":"post-20335","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-observatorio-moonmentum","8":"tag-ecliptica","9":"tag-la-serpiente","10":"tag-mitologia","11":"tag-observatorio-moonmentum","12":"tag-ofiuco","13":"tag-ofiuco-y-serpens","14":"tag-serpens"},"_links":{"self":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts\/20335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/comments?post=20335"}],"version-history":[{"count":0,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts\/20335\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/media\/161797"}],"wp:attachment":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/media?parent=20335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/categories?post=20335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/tags?post=20335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}