{"id":225599,"date":"2021-02-15T15:39:05","date_gmt":"2021-02-15T19:39:05","guid":{"rendered":"https:\/\/moonmentum.com\/blog\/?p=225599"},"modified":"2021-02-15T16:05:02","modified_gmt":"2021-02-15T20:05:02","slug":"juego-de-dioses","status":"publish","type":"post","link":"https:\/\/moonmentum.com\/blog\/archivo\/carrusel\/juego-de-dioses\/","title":{"rendered":"Juego de Dioses?"},"content":{"rendered":"<p>Mirar la propia realidad sin entenderla, es similar a contemplar un partido de ajedrez entre dos grandes maestros, sin conocer las reglas del juego. El cient\u00edfico Richard Feynman describe esta situaci\u00f3n se\u00f1alando.<\/p>\n<p><span style=\"color: #808080;\">\u00bfQu\u00e9 queremos decir con \u201ccomprender\u201d algo? Imagino que el mundo es parecido a una gran partida de ajedrez que juegan los dioses, y que nosotros somos observadores del juego. No sabemos cu\u00e1les son las reglas del juego; todo lo que nos est\u00e1 permitido es observarlo. Por supuesto, si observamos durante un lapso suficiente, con el tiempo podr\u00edamos captar algunas reglas. Las reglas del juego son lo que llamamos f\u00edsica fundamental. Sin embargo, incluso si las conoci\u00e9ramos todas, puede que no fu\u00e9ramos capaces de entender por qu\u00e9 se hace un determinado movimientos durante el juego; es, simplemente, demasiado complicado y muy limitada nuestra mente.<\/span><\/p>\n<p><span style=\"color: #808080;\">Si juegan ajedrez, sabr\u00e1n que es f\u00e1cil aprender todas las reglas, y no obstante suele ser muy dif\u00edcil elegir el mejor movimiento o comprender por qu\u00e9 un competidor juega como lo hace. Lo mismo sucede en la naturaleza, s\u00f3lo que en mucho mayor grado. Nos debemos limitar al asunto m\u00e1s b\u00e1sico, a las reglas del juego. Si las conocemos, consideramos que \u201ccomprendemos\u201d el mundo.<\/span><\/p>\n<p>El Carnaval es parte de un juego, un juego de Dioses que ahora es dirigido por humanos.<\/p>\n<p>El aspecto m\u00e1s llamativo del Carnaval.<\/p>\n<p>En el ciclo carnavalesco se ha venido unificando la religiosidad popular con lo festivo, pero tambi\u00e9n con la farsa y lo dionis\u00edaco. El Carnaval es la fiesta de la burla, la broma, la algaraza, la chanza, la risa, la parodia y el humor.<\/p>\n<p>El Carnaval sigue siendo hoy una \u201cv\u00e1lvula de escape\u201d para las diversas tensiones sociales. <strong>El poder lo sabe y consiente que se d\u00e9 una libertad inusual desde el Jueves Lardero al Mi\u00e9rcoles de Ceniza,<\/strong> pero est\u00e1 vigilante y llega incluso a reglamentar y programar los diversos actos carnavalescos, a trav\u00e9s de comisiones de festejos o de cultura. Incluso subvenciona en parte el Carnaval, circunstancia ir\u00f3nica para cualquier an\u00e1lisis etnogr\u00e1fico que ve en el Carnaval genuino algo surgido del pueblo y para el pueblo, en oposici\u00f3n a todo tipo de poder establecido.<\/p>\n<p>De esta forma se consigue el equilibrio social, como se pone de manifiesto el Mi\u00e9rcoles de Ceniza. Todo vuelve a su orden y cada estamento social recobra su lugar, \u201cTodo pasa. Al final, da el pobre con su pobreza, torna el rico a su riqueza, el cura vuelve a sus misas\u201d.<\/p>\n<p>Quiz\u00e1s el Poder logra este retorno a la normalidad debido a la carga arquet\u00edpica del Carnaval, en el que el Caos es vencido por el Cosmos, como sucede en las cosmogon\u00edas, y que tiene en el festejo del Carnaval su expresi\u00f3n m\u00e1s gr\u00e1fica con la victoria de Do\u00f1a Cuaresma y la muerte de Don Carnal, en sus diversas manifestaciones y nombres (entierro de la sardina, quema del pelele, etc).<\/p>\n<p>De esta forma se actualiza el antiguo ritual de la muerte del \u201cRey del \u00danico D\u00eda\u201d o \u201cSaturnalicius rex\u201d. El simbolismo arquet\u00edpico es claro: con el Carnaval muerto, sacrificado cual \u201cchivo expiatorio\u201d, renace el pueblo y desaparece la crudeza del invierno con sus limitaciones.<sup class='footnote'><a href='#fn-225599-1' id='fnref-225599-1' onclick='return fdfootnote_show(225599)'>1<\/a><\/sup><\/p>\n<p>&nbsp;<\/p>\n<div class='footnotes' id='footnotes-225599'>\n<div class='footnotedivider'><\/div>\n<ol>\n<li id='fn-225599-1'>\u00a0Libros consultados\n<p>CARO BAROJA, Julio:\u00a0El Carnaval, Ed. Taurus, Madrid, 1965,<br \/>\nCARDINI, Franco:\u00a0D\u00edas Sagrados, Argos Vergara, Barcelona, 1984.<br \/>\nELIADE, Mircea:\u00a0El mito del Eterno Retorno, Emec\u00e9 Ed., Buenos Aires, 1968.<br \/>\nJUNG, C.G.:\u00a0Recuerdos, sue\u00f1os, pensamientos, Seix Barral, Barcelona, 3\u00aa ed., 1981<br \/>\nMALDONADO, Luis:\u00a0Religiosidad popular, Ed. Cristiandad <span class='footnotereverse'><a href='#fnref-225599-1'>&#8617;<\/a><\/span><\/li>\n<\/ol>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Mirar la propia realidad sin entenderla, es similar a contemplar un partido de ajedrez entre dos grandes maestros, sin conocer las reglas del juego. El cient\u00edfico Richard Feynman describe esta situaci\u00f3n se\u00f1alando. \u00bfQu\u00e9 queremos decir con \u201ccomprender\u201d algo? Imagino que el mundo es parecido a una gran partida de ajedrez que juegan los dioses, y [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":191869,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14636,8124,14635],"tags":[],"class_list":["post-225599","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad","category-carrusel","category-sabias-que"],"_links":{"self":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts\/225599","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/comments?post=225599"}],"version-history":[{"count":0,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts\/225599\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/media\/191869"}],"wp:attachment":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/media?parent=225599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/categories?post=225599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/tags?post=225599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}