{"id":36579,"date":"2010-11-07T00:07:31","date_gmt":"2010-11-07T04:37:31","guid":{"rendered":"http:\/\/www.moonmentum.com\/blog\/?p=36579"},"modified":"2013-06-03T16:29:07","modified_gmt":"2013-06-03T20:59:07","slug":"rompiendo-ciclos","status":"publish","type":"post","link":"https:\/\/moonmentum.com\/blog\/pronostico\/clima-astrologico\/rompiendo-ciclos\/","title":{"rendered":"Rompiendo Ciclos"},"content":{"rendered":"<p><a href=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2010\/11\/c5baa96a991a35bfbb1b56147091dc87.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-36588 lazyload\" style=\"--smush-placeholder-width: 230px; --smush-placeholder-aspect-ratio: 230\/300;float: left; margin: 6px; border: 0pt none;\" title=\"missingyoubz7\" data-src=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2010\/11\/c5baa96a991a35bfbb1b56147091dc87-230x300.jpg\" alt=\"missingyoubz7\" width=\"230\" height=\"300\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><noscript><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-36588\" style=\"float: left; margin: 6px; border: 0pt none;\" title=\"missingyoubz7\" src=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2010\/11\/c5baa96a991a35bfbb1b56147091dc87-230x300.jpg\" alt=\"missingyoubz7\" width=\"230\" height=\"300\" \/><\/noscript><\/a>La vida tiene una naturaleza c\u00edclica imposible de ignorar, as\u00ed como tus abuelos trataron a tus padres ellos aprendieron como ser (o no ser) buenos padres, intentando hacerlo as\u00ed contigo \u00a0y luego tu har\u00e1s lo mismo a tus hijos.<\/p>\n<p>Incluso si tratas de romper el ciclo por puro capricho, esa conducta garantizar\u00e1 la perpetuaci\u00f3n del mismo, mientras m\u00e1s luches en su contra m\u00e1s r\u00e1pido acercas a ti el futuro que estas tratando de evitar.<\/p>\n<p>La \u00fanica forma de hacer un cambio, es haciendo dos cosas:<\/p>\n<p>1.\u00a0\u00a0\u00a0\u00a0 <strong>Perdonando<\/strong>: Independiente de las razones o motivos por los cuales las personas de tu pasado te han lastimado, la \u00fanica forma de eliminar el ciclo es con el incre\u00edble poder del perd\u00f3n. \u00bfCon que prop\u00f3sito guardar rencor? Simplemente deja el pasado ir y perm\u00edtete progresar.<\/p>\n<p>2.\u00a0\u00a0\u00a0\u00a0 <strong>Aprendiendo<\/strong>: \u00bfQu\u00e9 lecci\u00f3n ten\u00eda el universo para ti? Hazte esa pregunta y descubre que ten\u00eda el destino en ese momento entre manos.<\/p>\n<p>Hoy, aplica esas dos cosas y rompe los ciclos.<!--more--><\/p>\n<p style=\"text-align: right;\"><span style=\"color: #888888;\">\u201cDebemos darnos cuenta que no es la felicidad la que nos hace ser agradecidos, sino la gratitud la que nos hace ser felices\u201d.<\/span><\/p>\n<p>Lee con mucha atenci\u00f3n nuestra secci\u00f3n <strong><a href=\"..\/pronostico\/formula\/catarsis-6\/\">Astrolog\u00eda al d\u00eda<\/a><\/strong><\/p>\n<h2><strong>Ant\u00eddotos<\/strong><\/h2>\n<ul>\n<li>Escucha las Frecuencias 528 Hz para reparar el ADN y la      741 Hz para despertar la      intuici\u00f3n.<\/li>\n<li>Si tienes tu kit de <strong>Flores de Bach<\/strong> equilibra las energ\u00edas:<\/li>\n<\/ul>\n<p><span style=\"color: #888888;\">&#8211; <strong>Mustard: <\/strong>Depresi\u00f3n y tristezas de causas desconocidas, que aparecen y desaparecen sin motivo.<\/span><\/p>\n<p><span style=\"color: #888888;\">&#8211; <strong>Sclerantus: <\/strong>Indecisi\u00f3n entre dos extremos opuestos.<\/span><\/p>\n<ul>\n<li><strong><a href=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2010\/11\/08475fdbdf064b95c62ceddb90f50b88.gif\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-36395 lazyload\" style=\"--smush-placeholder-width: 90px; --smush-placeholder-aspect-ratio: 90\/89;float: left; margin: 6px; border: 0pt none;\" title=\"cuarzo-rutilado\" data-src=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2010\/11\/08475fdbdf064b95c62ceddb90f50b88-300x294.gif\" alt=\"cuarzo-rutilado\" width=\"90\" height=\"89\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><noscript><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-36395\" style=\"float: left; margin: 6px; border: 0pt none;\" title=\"cuarzo-rutilado\" src=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2010\/11\/08475fdbdf064b95c62ceddb90f50b88-300x294.gif\" alt=\"cuarzo-rutilado\" width=\"90\" height=\"89\" \/><\/noscript><\/a>Gemoterapia:<\/strong><strong> <\/strong><\/li>\n<\/ul>\n<p><span style=\"color: #888888;\">&#8211; <strong>Rutilado: <\/strong>Proporciona nuevas energ\u00edas a los corazones tristes y cansados. Da fuerza para enfrentarse a la realidad y es muy \u00fatil en las depresiones por fatiga. Ofrece una gran protecci\u00f3n contra campos electromagn\u00e9ticos y ondas nocivas. Aumenta y ordena el campo electromagn\u00e9tico vital, reconstruye agujeros del aura. Hace desaparecer el miedo.<\/span><br \/>\n<strong><\/strong><\/p>\n<ul>\n<li><strong>Ve la Pel\u00edcula: Madame Curie.<\/strong><\/li>\n<\/ul>\n<p style=\"text-align: center;\">\n<p><span style=\"color: #888888;\">El esp\u00edritu de la tierra dar\u00e1 a una mujer apasionada por la ciencia algunos de sus secretos y estos se convertir\u00e1n en el motivo de su vida y de su muerte.<\/span><\/p>\n<p><span style=\"color: #888888;\"><strong>Sinopsis<\/strong>:<\/span><\/p>\n<p><a href=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2010\/11\/30b55c1e85a975a147ed70bb106fbd59.gif\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-36592 lazyload\" style=\"--smush-placeholder-width: 197px; --smush-placeholder-aspect-ratio: 197\/300;margin: 6px; border: 0px;\" title=\"Madame Curie\" data-src=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2010\/11\/30b55c1e85a975a147ed70bb106fbd59-197x300.gif\" alt=\"Madame Curie\" width=\"197\" height=\"300\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><noscript><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-36592\" style=\"margin: 6px; border: 0px;\" title=\"Madame Curie\" src=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2010\/11\/30b55c1e85a975a147ed70bb106fbd59-197x300.gif\" alt=\"Madame Curie\" width=\"197\" height=\"300\" \/><\/noscript><\/a><span style=\"color: #888888;\">Madame Curie (1943) dirigida por Mervyn LeRoy y basada en el libro escrito por su nieta \u00c8ve Curie (Interpretada por Gigi Perreau). Nominada para 7 Oscars.<\/span><\/p>\n<p><span style=\"color: #888888;\">La Joven polaca estudiante de qu\u00edmica y f\u00edsica en la Sorbona Maria Sk\u0142odowska, se casa con el doctor Pierre Curie. Ella ha trabajado durante un tiempo en su laboratorio para su maestr\u00eda en f\u00edsica. Alli se conocieron y pronto se enamoraron.<\/span><\/p>\n<p><span style=\"color: #888888;\">En su luna de miel deciden averiguar qu\u00e9 caus\u00f3 el extra\u00f1o efecto que descubri\u00f3 el profesor Becquerel (Reginald Owen) con las piedras torio\/uranio para su tesis. A\u00f1os de minuciosa investigaci\u00f3n y experimentaci\u00f3n llevar\u00e1n \u00a0Marie (Greer Garson) y Pierre (Walter Pidgeon) Curie a identificar como el radio.<\/span><\/p>\n<p><a href=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2010\/11\/mariecurie1943.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-36593 lazyload\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;margin: 6px; border: 0px;\" title=\"Marie Curie 1943\" data-src=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2010\/11\/MarieCurie1943-150x150.png\" alt=\"Marie Curie 1943\" width=\"150\" height=\"150\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><noscript><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-36593\" style=\"margin: 6px; border: 0px;\" title=\"Marie Curie 1943\" src=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2010\/11\/MarieCurie1943-150x150.png\" alt=\"Marie Curie 1943\" width=\"150\" height=\"150\" \/><\/noscript><\/a><span style=\"color: #888888;\">Lamentablemente, Pierre muri\u00f3 cruzando la calle bajo la lluvia cuando fue atropellado por un caballo y una carreta, pero la historia ya hab\u00eda hablado, adem\u00e1s de su romance y su pasi\u00f3n Marie y Pierre compartir\u00e1n el Premio Nobel de F\u00edsica por sus descubrimientos.<\/span><\/p>\n<p><span style=\"color: #888888;\">En 1891 Marie se traslad\u00f3 a Par\u00eds para continuar sus estudios ah\u00ed fund\u00f3 el prestigioso Instituto Curie. Fue madre de Ir\u00e8ne Joliot-Curie (Margaret O&#8217;Brien 5 a\u00f1os)\u00a0tambi\u00e9n galardonada con el Premio Nobel, junto a su marido Fr\u00e9d\u00e9ric Joliot. Marie, Ir\u00e8ne y su esposo Fr\u00e9d\u00e9ric murieron de enfermedades relacionadas con el manejo de elementos radioactivos.<\/span><\/p>\n<p><span style=\"color: #888888;\"><em>Veamos \u00a0dos grandes pasiones, la ciencia y su esposo, convertirse en el centro de la vida de Marie en \u201cMadame Curie\u201d.<\/em><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La vida tiene una naturaleza c\u00edclica imposible de ignorar, as\u00ed como tus abuelos trataron a tus padres ellos aprendieron como ser (o no ser) buenos padres, intentando hacerlo as\u00ed contigo \u00a0y luego tu har\u00e1s lo mismo a tus hijos. Incluso si tratas de romper el ciclo por puro capricho, esa conducta garantizar\u00e1 la perpetuaci\u00f3n del [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":36588,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[5982,920,1184,1357,6783,1693,3200,587,1222,7683,7682],"class_list":["post-36579","post","type-post","status-publish","format-standard","has-post-thumbnail","category-clima-astrologico","tag-adn","tag-antidoto","tag-antidotos","tag-flores-de-bach","tag-frecuencia-528-hz","tag-inspirar","tag-pelicula","tag-recomendaciones","tag-recomendaciones-astrologicas","tag-rutilado","tag-sclerantus"],"_links":{"self":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts\/36579","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/comments?post=36579"}],"version-history":[{"count":0,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts\/36579\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/media\/36588"}],"wp:attachment":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/media?parent=36579"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/categories?post=36579"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/tags?post=36579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}