	<style type="text/css">
		.postTabs_divs{
	padding: 4px;	
}


.postTabs_titles{
	display:none;	
}

ul.postTabs
	{
	margin:0px 0px 1em !important;
	padding: 0.2em 1em 0.2em 20px !important;
	border-bottom: 1px solid #ccc !important;
	font-size: 14px;
	list-style-type: none !important;
	line-height:normal;
	text-align: left;
	display: block !important;
	background: none;
	}

ul.postTabs li
	{	
	display: inline !important;
	font-size: 14px;
	line-height:normal;
	background: none;
	padding: 0px;
	margin: 0px;
	}
  
ul.postTabs li:before{
content: none;	
}  
  	
ul.postTabs li a
	{
	text-decoration: none;
	background: #808080;
	border: 1px solid #ccc  !important;
	padding: 0.2em 0.4em !important;
	color: #ffffff !important;
	outline:none;	
	cursor: pointer;
	
	}
	
ul.postTabs li.postTabs_curr a{
	border-bottom: 1px solid #fff  !important;
	background: #fff;
	color: #000000 !important;
	text-decoration: none;
	
	}

ul.postTabs li a:hover
	{
	color: #666 !important;
	background: #d4d4d4;
	text-decoration: none;
	
	}

.postTabsNavigation{
	display: block !important;
	overflow:hidden;
}

.postTabs_nav_next{
	float:right;
}

.postTabs_nav_prev{
	float:left;
}

@media screen and (max-width: 699px) {
	ul.postTabs li {
		display: block !important;
		width: 100%;
		margin: -3px;
	}
	ul.postTabs li a {
		display: block;
		width: 96%;
	}
}	</style>
	{"id":41862,"date":"2011-01-22T00:07:06","date_gmt":"2011-01-22T04:37:06","guid":{"rendered":"http:\/\/www.moonmentum.com\/blog\/?p=41862"},"modified":"2013-06-07T16:51:31","modified_gmt":"2013-06-07T21:21:31","slug":"corre-corre-corre","status":"publish","type":"post","link":"https:\/\/moonmentum.com\/blog\/pronostico\/clima-astrologico\/corre-corre-corre\/","title":{"rendered":"Corre\u2026 Corre\u2026 Corre."},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-41876 alignleft lazyload\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/225;margin: 6px; border: 0px;\" title=\"Corre caminos y Wilie E. Coyote\" data-src=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2011\/01\/road-runner-wile-e-coyote-300x225.jpg\" alt=\"Corre caminos y Wilie E. Coyote\" width=\"300\" height=\"225\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><noscript><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-41876 alignleft\" style=\"margin: 6px; border: 0px;\" title=\"Corre caminos y Wilie E. Coyote\" src=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2011\/01\/road-runner-wile-e-coyote-300x225.jpg\" alt=\"Corre caminos y Wilie E. Coyote\" width=\"300\" height=\"225\" \/><\/noscript><\/p>\n<p>Mito y leyenda, ciencia y maravilla, un fen\u00f3meno generacional que ha fascinado a cientos de personas polarizando a sus observadores en dos bandos atra\u00eddos por los personajes de una eterna carrera por sobrevivir. La energ\u00eda de Aries representada en la acci\u00f3n guerrera de cazar y escapar.<\/p>\n<p><strong>Correcaminos <\/strong>(<em>Ultra-Sonicus Ad Infinitum) <\/em>entre otros muchos \u201cnombres cient\u00edficos\u201d, y <strong>Coyote<\/strong> (<em>Nemesis Riduclii<\/em>) uno de los menos peyorativos que se le dio al personaje, dos tipos diferentes de maravillas enfrentadas en una heroica lucha.<!--more--><\/p>\n<p>El Coyote, del n\u00e1huatl \u00ab<em>c\u00f3yotl\u00bb<\/em>, es una de las pocas criaturas en la tierra que han expandido su territorio a pesar del hombre, y la expansi\u00f3n es una actividad asociada a J\u00fapiter. En la caricatura el coyote es un genio en la invenci\u00f3n, utiliza su imaginaci\u00f3n y su inteligencia para perseguir su objetivo, se le asocia con velocidad constante, tenaz perseguidor, catalogado de testarudo una actitud muy humana. En la realidad puede mantener ritmo hasta llegar a su l\u00edmite. Es un animal muy flaco que puede parecer desnutrido aun si goza de buena salud. Con cada comienzo (Aries) Wilie E. Coyote tendr\u00e1 nuevas y mejores ideas con un enfoque cient\u00edfico para capturar a su rival digno del mejor ingeniero.<\/p>\n<p>El Correcaminos, por su parte, es un ser ex\u00f3tico, casi mitol\u00f3gico, descendiente del ave de piernas largas y con cresta que concuerda con la descripci\u00f3n de Plat\u00f3n (del Abraxis de Mysia). M\u00e1gico, et\u00e9reo, r\u00e1pido, con su aceleraci\u00f3n que desaf\u00eda las leyes de la f\u00edsica creando una suerte de v\u00f3rtice que le rodea. Con una misteriosa misi\u00f3n, sin pensar, ni preocuparse por su destino. Escapando sin cesar de su depredador, siempre viviendo de prisa, siempre viajando. B\u00e1sicamente energ\u00e9tico que es tambi\u00e9n un aspecto de J\u00fapiter. En la comiquita se le otorga el roll de vencedor.<\/p>\n<p>Ambos tienen su club de fan en Facebook, ambos tienen sus admiradores, ambos corrieron juntos hacia el \u00e9xito y ambos representan actitudes humanas. Cada uno tiene su posici\u00f3n en un mundo que divide su coraz\u00f3n entre estos dos h\u00e9roes ganadores, del brillo de su \u00e9xito casi sin palabras en una carrera con un profundo contenido.<\/p>\n<p><strong>Recomendaciones<\/strong><\/p>\n<ul>\n<li>Hoy contempla la naturaleza y d\u00e9jate guiar por tu intuici\u00f3n.<\/li>\n<li>A las 12:12 pm EST contempla el Sol, ya que \u00e9l estar\u00e1 recibiendo energ\u00eda directa de J\u00fapiter.<\/li>\n<li>V\u00edstete de azul.<\/li>\n<li>Col\u00f3cate una prenda de color rojo.<\/li>\n<li>Lleva contigo un frasquito con semillas de<a href=\"\/blog\/?p=41863\"> S\u00e9samo o Ajonjol\u00ed<\/a>.<\/li>\n<li>Eleva tu energ\u00eda en el paso de J\u00fapiter a Aries\u2026 viendo <strong>\u201cEl Correcaminos\u201d<\/strong>.<\/li>\n<\/ul>\n<p><a href=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2011\/01\/el-correcaminos-4.gif\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-41889 lazyload\" style=\"--smush-placeholder-width: 168px; --smush-placeholder-aspect-ratio: 168\/300;margin: 6px; border: 0px;\" title=\"El correcaminos\" data-src=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2011\/01\/El-correcaminos-4-168x300.gif\" alt=\"El correcaminos\" width=\"168\" height=\"300\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><noscript><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-41889\" style=\"margin: 6px; border: 0px;\" title=\"El correcaminos\" src=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2011\/01\/El-correcaminos-4-168x300.gif\" alt=\"El correcaminos\" width=\"168\" height=\"300\" \/><\/noscript><\/a>J\u00fapiter entra en Aries el sol se encuentra en Sol en Acuario en conjunci\u00f3n con Marte, tendremos un tsunami energ\u00e9tico. Debemos hacer catarsis y canalizar el exceso de energ\u00edas de estos d\u00edas, es por ello que seleccionamos una cruenta persecuci\u00f3n sin cuartel en la que ambos bandos utilizan todo recurso de su parte para vencer en la batalla al enemigo. Explosiones y explosivos, cohetes, trenes, camiones y autos. Tambi\u00e9n ca\u00eddas, golpes, derrumbes atropellamientos. Vendas fracturas y quemaduras producto de espectaculares planes cuidadosamente ejecutados.<\/p>\n<p>Una batalla entre salvar la vida y la urgencia por ingerir alimentos.<\/p>\n<p>El Coyote y Correcaminos (1948) director Chuck Jones para Warner Bros.,<\/p>\n<p>En un desierto al suroeste de EE.UU. habita el Correcaminos (<em>Velocitus delectiblus<\/em>) \u00a0un ave de alto octanaje con una velocidad que recuerda a Mercurio que recorre el desierto a toda prisa por razones desconocidas. Es tan r\u00e1pido que al pasar por una carretera es capaz de ondular el pavimento o las marcas de este al tomar una curva. Pese a su velocidad es capaz de parar en una fracci\u00f3n de segundo. Anuncia su presencia con un extra\u00f1o Beep, Beep (que suena m\u00e1s como Meep, Meep).<\/p>\n<p>Esta veloz ave es perseguida de un modo implacable por su feroz enemigo el inteligente y tenaz Wilie E. Coyote un coyote hambriento que a pesar de creerse un genio, en repetidas ocasiones no atrapar al coger el Correcaminos con sus planos, suministros sin fin de aparatos de \u201cACME Corporation\u201d, armas y dem\u00e1s inventos.<\/p>\n<p>Luchemos del lado de nuestro personaje preferido, Coyote o Correcaminos para canalizar y catalizar el exceso de energ\u00eda viendo \u201cEl Correcaminos\u201d<\/p>\n<p><ul id='postTabs_ul_41862' class='postTabs' style='display:none'>\n<li id='postTabs_li_0_41862' class='postTabs_curr'><a  id=\"41862_0\" onMouseOver=\"posTabsShowLinks('Tradicional 1'); return true;\"  onMouseOut=\"posTabsShowLinks();\"  class='postTabsLinks'>Tradicional 1<\/a><\/li>\n<li id='postTabs_li_1_41862' ><a  id=\"41862_1\" onMouseOver=\"posTabsShowLinks('Tradicional 2'); return true;\"  onMouseOut=\"posTabsShowLinks();\"  class='postTabsLinks'>Tradicional 2<\/a><\/li>\n<li id='postTabs_li_2_41862' ><a  id=\"41862_2\" onMouseOver=\"posTabsShowLinks('Tradicional 3'); return true;\"  onMouseOut=\"posTabsShowLinks();\"  class='postTabsLinks'>Tradicional 3<\/a><\/li>\n<li id='postTabs_li_3_41862' ><a  id=\"41862_3\" onMouseOver=\"posTabsShowLinks('Tradicional 4'); return true;\"  onMouseOut=\"posTabsShowLinks();\"  class='postTabsLinks'>Tradicional 4<\/a><\/li>\n<li id='postTabs_li_4_41862' ><a  id=\"41862_4\" onMouseOver=\"posTabsShowLinks('Nuevo 1'); return true;\"  onMouseOut=\"posTabsShowLinks();\"  class='postTabsLinks'>Nuevo 1<\/a><\/li>\n<li id='postTabs_li_5_41862' ><a  id=\"41862_5\" onMouseOver=\"posTabsShowLinks('Nuevo 2'); return true;\"  onMouseOut=\"posTabsShowLinks();\"  class='postTabsLinks'>Nuevo 2<\/a><\/li>\n<li id='postTabs_li_6_41862' ><a  id=\"41862_6\" onMouseOver=\"posTabsShowLinks('Nuevo 3'); return true;\"  onMouseOut=\"posTabsShowLinks();\"  class='postTabsLinks'>Nuevo 3<\/a><\/li>\n<\/ul>\n\n<div class='postTabs_divs postTabs_curr_div' id='postTabs_0_41862'>\n<span class='postTabs_titles'><b>Tradicional 1<\/b><\/span><\/p>\n<p style=\"text-align: center;\">\n<p><\/div>\n\n<div class='postTabs_divs' id='postTabs_1_41862'>\n<span class='postTabs_titles'><b>Tradicional 2<\/b><\/span><\/p>\n<p style=\"text-align: center;\"><object classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" width=\"500\" height=\"405\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"allowscriptaccess\" value=\"always\" \/><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/zXyz5WkVj_o&amp;hl=es_ES&amp;fs=1&amp;\" \/><param name=\"allowfullscreen\" value=\"true\" \/><embed type=\"application\/x-shockwave-flash\" width=\"500\" height=\"405\" src=\"http:\/\/www.youtube.com\/v\/zXyz5WkVj_o&amp;hl=es_ES&amp;fs=1&amp;\" allowscriptaccess=\"always\" allowfullscreen=\"true\"><\/embed><\/object><\/p>\n<p><\/div>\n\n<div class='postTabs_divs' id='postTabs_2_41862'>\n<span class='postTabs_titles'><b>Tradicional 3<\/b><\/span><\/p>\n<p style=\"text-align: center;\">\n<p><\/div>\n\n<div class='postTabs_divs' id='postTabs_3_41862'>\n<span class='postTabs_titles'><b>Tradicional 4<\/b><\/span><\/p>\n<p style=\"text-align: center;\"><object classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" width=\"500\" height=\"405\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"allowscriptaccess\" value=\"always\" \/><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/dW0q1aI1kQw&amp;hl=es_ES&amp;fs=1&amp;\" \/><param name=\"allowfullscreen\" value=\"true\" \/><embed type=\"application\/x-shockwave-flash\" width=\"500\" height=\"405\" src=\"http:\/\/www.youtube.com\/v\/dW0q1aI1kQw&amp;hl=es_ES&amp;fs=1&amp;\" allowscriptaccess=\"always\" allowfullscreen=\"true\"><\/embed><\/object><\/p>\n<p><\/div>\n\n<div class='postTabs_divs' id='postTabs_4_41862'>\n<span class='postTabs_titles'><b>Nuevo 1<\/b><\/span><\/p>\n<p style=\"text-align: center;\">\n<p><\/div>\n\n<div class='postTabs_divs' id='postTabs_5_41862'>\n<span class='postTabs_titles'><b>Nuevo 2<\/b><\/span><\/p>\n<p style=\"text-align: center;\">\n<p><\/div>\n\n<div class='postTabs_divs' id='postTabs_6_41862'>\n<span class='postTabs_titles'><b>Nuevo 3<\/b><\/span><\/p>\n<p style=\"text-align: center;\"><object classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" width=\"500\" height=\"311\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"allowscriptaccess\" value=\"always\" \/><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/b8Q-OrFcV1s&amp;hl=es_ES&amp;fs=1&amp;\" \/><param name=\"allowfullscreen\" value=\"true\" \/><embed type=\"application\/x-shockwave-flash\" width=\"500\" height=\"311\" src=\"http:\/\/www.youtube.com\/v\/b8Q-OrFcV1s&amp;hl=es_ES&amp;fs=1&amp;\" allowscriptaccess=\"always\" allowfullscreen=\"true\"><\/embed><\/object><\/p>\n<p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Mito y leyenda, ciencia y maravilla, un fen\u00f3meno generacional que ha fascinado a cientos de personas polarizando a sus observadores en dos bandos atra\u00eddos por los personajes de una eterna carrera por sobrevivir. La energ\u00eda de Aries representada en la acci\u00f3n guerrera de cazar y escapar. Correcaminos (Ultra-Sonicus Ad Infinitum) entre otros muchos \u201cnombres cient\u00edficos\u201d, [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":41876,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[8504,8503,8505],"class_list":{"0":"post-41862","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-clima-astrologico","8":"tag-el-correcaminos","9":"tag-sesamo-o-ajonjoli","10":"tag-vistete-de-azul"},"_links":{"self":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts\/41862","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/comments?post=41862"}],"version-history":[{"count":0,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts\/41862\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/media\/41876"}],"wp:attachment":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/media?parent=41862"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/categories?post=41862"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/tags?post=41862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}