{"id":53957,"date":"2011-06-13T00:08:24","date_gmt":"2011-06-13T04:38:24","guid":{"rendered":"http:\/\/www.moonmentum.com\/blog\/?p=53957"},"modified":"2011-06-14T09:02:08","modified_gmt":"2011-06-14T13:32:08","slug":"el-cazador-de-serpientes-abre-nuevamente-su-espectaculo","status":"publish","type":"post","link":"https:\/\/moonmentum.com\/blog\/actualidad\/observatorio-moonmentum\/el-cazador-de-serpientes-abre-nuevamente-su-espectaculo\/","title":{"rendered":"El cazador de serpientes abre nuevamente su espect\u00e1culo."},"content":{"rendered":"<p><a rel=\"attachment wp-att-53964\" href=\"http:\/\/www.moonmentum.com\/blog\/energia-protagonica\/observatorio-moonmentum\/el-cazador-de-serpientes-abre-nuevamente-su-espectaculo\/attachment\/ophiuchus-blog-victor-javier\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-53964 lazyload\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/238;border: 0pt none; margin: 6px; float: left;\" title=\"Ophiuchus - Blog - Victor Javier\" data-src=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2011\/06\/Ophiuchus-Blog-Victor-Javier-300x238.jpg\" alt=\"Ophiuchus - Blog - Victor Javier\" width=\"300\" height=\"238\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><noscript><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-53964\" style=\"border: 0pt none; margin: 6px; float: left;\" title=\"Ophiuchus - Blog - Victor Javier\" src=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2011\/06\/Ophiuchus-Blog-Victor-Javier-300x238.jpg\" alt=\"Ophiuchus - Blog - Victor Javier\" width=\"300\" height=\"238\" \/><\/noscript><\/a>H\u00e9rcules y Ofiuco se encuentran cara a cara en el oriente esta noche. Cada uno recibe el nombre \u00e1rabe que significa \u00abcabeza\u00bb. En H\u00e9rcules es Ras Algethi (cabeza del arrodillado); en Ofiuco, Ras Alhague (cabeza del domador de serpientes).<br \/>\n<strong> <\/strong><\/p>\n<p><strong>Mu Herculis<sub> <\/sub><\/strong><br \/>\nH\u00e9rcules, el hombre fuerte, es una constelaci\u00f3n grande que no hace honor a su nombre. A pesar de ello, H\u00e9rcules alberga una estrella interesante que, en cierto sentido, parece ser una versi\u00f3n m\u00e1s antigua del Sol &#8212; y por eso es una estrella que habr\u00ed\u00ada tenido tiempo para producir vida inteligente.<\/p>\n<p>Mu Herculis est\u00e1 a s\u00f3lo 27 a\u00f1os luz. Es visible sin instrumentos \u00f3pticos pero, al igual que su constelaci\u00f3n, no es nada espectacular.\u00a0<!--more--><\/p>\n<p>La masa de Mu Herculis es similar a la del Sol y, al igual que el Sol, su superficie est\u00e1 sacudida por las peque\u00f1as vibraciones que recorren su interior. Del mismo modo que los terremotos ayudan a estudiar el interior de la Tierra, estos \u00abse\u00ed\u00adsmos\u00bb estelares ayudan a estudiar el interior de la estrella.<\/p>\n<p>Los se\u00ed\u00adsmos pueden incluso ayudar a determinar la edad de la estrella. Analizando las vibraciones, los astr\u00f3nomos calcularon recientemente que la estrella es unos dos mil millones de a\u00f1os m\u00e1s vieja que el Sol y la Tierra.<\/p>\n<p>En la Tierra, la vida inteligente tard\u00f3 miles de millones de a\u00f1os en desarrollarse. Como Mu Herculis es todav\u00ed\u00ada m\u00e1s vieja que la Tierra, ha habido mucho tiempo para que en sus planetas se desarrollara la vida inteligente.<\/p>\n<p>Hasta ahora, no se sabe si hay planetas, pero observaciones futuras pueden decirnos si Mu Herculis alberga otra civilizaci\u00f3n.<strong> <\/strong><\/p>\n<p><strong> <\/strong><\/p>\n<p><strong>Nota: <\/strong>Esta informaci\u00f3n s\u00f3lo es v\u00e1lida para el Hemisferio Norte.<strong> <\/strong><\/p>\n<p><strong> <\/strong><\/p>\n<p>\u00bf<em>Cu\u00e1ntas veces te detienes a observar lo que el cielo cada noche coloca en cartelera?\u2026 Recuerda el axioma que dice \u201cComo es arriba\u2026 es abajo\u201d\u2026 El cielo y las estrellas no son un adorno\u2026 son una realidad.<\/em><\/p>\n<p><strong><em>Observar<\/em><\/strong><em> nos conecta en un 30% con la energ\u00eda del Universo.<br \/>\n<strong>Imitar<\/strong> lo observado\u00a0 nos conecta en un 70% con la energ\u00eda del Universo\u2026<br \/>\n<strong>Emular<\/strong> lo observado nos convierte en la energ\u00eda.<\/em><\/p>\n<p><span style=\"color: #888888;\"><sup>Fuentes consultadas:<strong> <\/strong><a href=\"http:\/\/www.radiouniverso.org\/\" target=\"_blank\">universoonline.org<\/a>.<br \/>\nFoto: vjmiranda.blogspot.com<\/sup><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>H\u00e9rcules y Ofiuco se encuentran cara a cara en el oriente esta noche. Cada uno recibe el nombre \u00e1rabe que significa \u00abcabeza\u00bb. En H\u00e9rcules es Ras Algethi (cabeza del arrodillado); en Ofiuco, Ras Alhague (cabeza del domador de serpientes). Mu Herculis H\u00e9rcules, el hombre fuerte, es una constelaci\u00f3n grande que no hace honor a su [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":53964,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[919,2486,593,17199,401,3514,496,527],"class_list":{"0":"post-53957","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-observatorio-moonmentum","8":"tag-cielo","9":"tag-hercules","10":"tag-luna","11":"tag-mirando-las-estrellas","12":"tag-observatorio-mc-donald","13":"tag-ofiuco","14":"tag-sol","15":"tag-universo"},"_links":{"self":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts\/53957","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/comments?post=53957"}],"version-history":[{"count":0,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts\/53957\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/media\/53964"}],"wp:attachment":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/media?parent=53957"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/categories?post=53957"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/tags?post=53957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}