{"id":69576,"date":"2011-11-20T00:08:30","date_gmt":"2011-11-20T04:38:30","guid":{"rendered":"http:\/\/www.moonmentum.com\/blog\/?p=69576"},"modified":"2011-11-20T00:36:24","modified_gmt":"2011-11-20T05:06:24","slug":"leon-tolstoi-un-maestro-del-alma-2","status":"publish","type":"post","link":"https:\/\/moonmentum.com\/blog\/efemerides\/semilla-de-la-semana\/leon-tolstoi-un-maestro-del-alma-2\/","title":{"rendered":"Le\u00f3n Tolst\u00f3i: un maestro del alma."},"content":{"rendered":"<p><a rel=\"attachment wp-att-69580\" href=\"http:\/\/www.moonmentum.com\/blog\/efemerides\/semilla-del-dia\/leon-tolstoi-un-maestro-del-alma-2\/attachment\/420px-ilya_efimovich_repin_1844-1930_-_portrait_of_leo_tolstoy_1887\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-69580 lazyload\" style=\"--smush-placeholder-width: 210px; --smush-placeholder-aspect-ratio: 210\/300;float: left; margin: 6px; border: 0pt none;\" title=\"420px-Ilya_Efimovich_Repin_(1844-1930)_-_Portrait_of_Leo_Tolstoy_(1887)\" data-src=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2011\/11\/420px-ilya_efimovich_repin_1844-1930_-_portrait_of_leo_tolstoy_1887-210x300.jpg\" alt=\"420px-Ilya_Efimovich_Repin_(1844-1930)_-_Portrait_of_Leo_Tolstoy_(1887)\" width=\"210\" height=\"300\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" \/><noscript><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-69580\" style=\"float: left; margin: 6px; border: 0pt none;\" title=\"420px-Ilya_Efimovich_Repin_(1844-1930)_-_Portrait_of_Leo_Tolstoy_(1887)\" src=\"http:\/\/www.moonmentum.com\/blog\/wp-content\/uploads\/2011\/11\/420px-ilya_efimovich_repin_1844-1930_-_portrait_of_leo_tolstoy_1887-210x300.jpg\" alt=\"420px-Ilya_Efimovich_Repin_(1844-1930)_-_Portrait_of_Leo_Tolstoy_(1887)\" width=\"210\" height=\"300\" \/><\/noscript><\/a>\u201cHay quien cruza el bosque y s\u00f3lo ve le\u00f1a para el fuego\u201d.<br \/>\n<strong>Le\u00f3n Tolstoi<\/strong><\/p>\n<p>\u201cEnerg\u00eda viva que puedes plantar en tu vida\u201d<\/p>\n<p><em>Cada d\u00eda hay en el Universo una estela dejada por la acci\u00f3n de otros seres humanos que al igual que nosotros buscaban la excelencia. Hoy esa\u00a0 estela o\u00a0 \u201c<\/em><a href=\"..\/..\/category\/sextante\/category\/sextante\/en-un-dia-como-hoy\/\"><em>semilla del d\u00eda<\/em><\/a><em>\u201d fue sembrada por\u2026<\/em><\/p>\n<p><strong>Le\u00f3n Tolst\u00f3i<\/strong>, fue un novelista ruso ampliamente considerado como uno de los m\u00e1s grandes escritores de occidente y de la literatura mundial. Sus m\u00e1s famosas obras son <em>Guerra y Paz<\/em> y <em>Anna Kar\u00e9nina<\/em>, y son tenidas como la c\u00faspide del realismo. Sus ideas sobre la No Violencia, expresadas en libros como El Reino de Dios est\u00e1 en Vosotros tuvieron un profundo impacto en gente como Gandhi y Martin Luther King.<\/p>\n<p>Tolst\u00f3i<strong> <\/strong>tuvo una importante influencia en el desarrollo del pensamiento anarquista, concretamente, se considera que era un cristiano libertario. El te\u00f3rico anarquista Pedro Kropotkin lo cit\u00f3 en el art\u00edculo <em>Anarquismo<\/em> de la <em>Enciclopedia Brit\u00e1nica de 1911<\/em>. Una carta a un peri\u00f3dico hind\u00fa titulado \u201cCarta a un hind\u00fa\u201d desemboc\u00f3 en una larga correspondencia con Mohandas Gandhi, que estaba en Sud\u00e1frica, influyendo profundamente en Gandhi en el concepto de resistencia no violenta, un punto central de la visi\u00f3n del cristianismo de Tolst\u00f3i.<!--more--><\/p>\n<p>Fue uno de los mayores defensores del <strong>esperanto<\/strong>, y en sus \u00faltimos a\u00f1os tras varias crisis espirituales se convirti\u00f3 en una persona profundamente religiosa, criticando las instituciones eclesi\u00e1sticas en <em>Resurrecci\u00f3n<\/em>, lo que provoc\u00f3 su excomuni\u00f3n.<\/p>\n<p>Hijo del noble propietario y de la acaudalada princesa Mar\u00eda Volkonski, Tolst\u00f3i vivir\u00eda siempre escindido entre esos dos espacios simb\u00f3licos que son la gran urbe y el campo, pues si el primero representaba para \u00e9l el deleite, el derroche y el lujo de quienes ambicionaban brillar en sociedad, el segundo, por el que sinti\u00f3 devoci\u00f3n, era el lugar del laborioso alumbramiento de sus preclaros sue\u00f1os literarios.<\/p>\n<p>\u201cLa raz\u00f3n no me ha ense\u00f1ado nada. Todo lo que yo s\u00e9 me ha sido dado por el coraz\u00f3n\u201d<br \/>\n<strong>Le\u00f3n Tolstoi<\/strong><\/p>\n<p><sup><span style=\"color: #888888;\">Foto: Wikipedia.org<\/span><\/sup><strong><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cHay quien cruza el bosque y s\u00f3lo ve le\u00f1a para el fuego\u201d. Le\u00f3n Tolstoi \u201cEnerg\u00eda viva que puedes plantar en tu vida\u201d Cada d\u00eda hay en el Universo una estela dejada por la acci\u00f3n de otros seres humanos que al igual que nosotros buscaban la excelencia. Hoy esa\u00a0 estela o\u00a0 \u201csemilla del d\u00eda\u201d fue sembrada [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":69580,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[1639,12082,1204],"class_list":{"0":"post-69576","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-semilla-de-la-semana","8":"tag-esperanto","9":"tag-fue-un-novelista-ruso","10":"tag-leon-tolstoi"},"_links":{"self":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts\/69576","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/comments?post=69576"}],"version-history":[{"count":0,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts\/69576\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/media\/69580"}],"wp:attachment":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/media?parent=69576"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/categories?post=69576"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/tags?post=69576"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}