{"id":94232,"date":"2012-05-12T00:18:36","date_gmt":"2012-05-12T04:48:36","guid":{"rendered":"http:\/\/www.moonmentum.com\/blog\/?p=94232"},"modified":"2012-05-12T02:14:01","modified_gmt":"2012-05-12T06:44:01","slug":"cancer-12-y-13-de-mayo","status":"publish","type":"post","link":"https:\/\/moonmentum.com\/blog\/horoscopo-de-la-semana\/cancer\/cancer-12-y-13-de-mayo\/","title":{"rendered":"C\u00e1ncer 12 y 13 de Mayo"},"content":{"rendered":"<p>La Luna se estar\u00e1 moviendo de tu casa 8 a tu casa 9 trayendo importantes oportunidades relacionadas con el extranjero, con el internet, y con las redes sociales. D\u00edas de <a href=\"http:\/\/www.moonmentum.com\/blog\/pronostico\/index\/abre-tu-mente-al-espiritu-visionario\/\" target=\"_blank\">consolidaci\u00f3n<\/a>.<\/p>\n<p>V\u00edstete\u00a0 o conecta con ropa muy c\u00f3moda de tu elecci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ff6600;\"><em>S\u00edguenos<\/em><em> en twitter por <strong><a href=\"https:\/\/twitter.com\/#!\/moonmentum\" target=\"_blank\">@Moonmentum<\/a> . . .<\/strong><\/em><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Luna se estar\u00e1 moviendo de tu casa 8 a tu casa 9 trayendo importantes oportunidades&#8230;<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[929],"tags":[8515,1719,585,9793,640,17210,8614,9291,343,17200,9634,1561,9795,793,1900,600],"class_list":{"0":"post-94232","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-cancer","7":"tag-12-signos-del-zodiaco","8":"tag-astrologa-lourdes-mendez","9":"tag-astrologia","10":"tag-astrologia-cancer","11":"tag-astros","12":"tag-cancer","13":"tag-horoscopo-cancer","14":"tag-horoscopo-diario","15":"tag-lourdes-mendez","16":"tag-reality-horoscope","17":"tag-signo-cancer","18":"tag-signo-zodiacal","19":"tag-signo-zodiacal-cancer","20":"tag-signos","21":"tag-signos-del-zodiaco","22":"tag-zodiaco"},"_links":{"self":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts\/94232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/comments?post=94232"}],"version-history":[{"count":0,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts\/94232\/revisions"}],"wp:attachment":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/media?parent=94232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/categories?post=94232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/tags?post=94232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}