{"id":98614,"date":"2012-06-09T00:10:31","date_gmt":"2012-06-09T04:40:31","guid":{"rendered":"http:\/\/www.moonmentum.com\/blog\/?p=98614"},"modified":"2012-06-09T02:09:27","modified_gmt":"2012-06-09T06:39:27","slug":"piscis-09-y-10-de-junio","status":"publish","type":"post","link":"https:\/\/moonmentum.com\/blog\/horoscopo-de-la-semana\/piscis\/piscis-09-y-10-de-junio\/","title":{"rendered":"Piscis 09 y 10 de Junio"},"content":{"rendered":"<p>La Luna desde tu signo, junto a Neptuno (tu regente) y en un poderos\u00edsimo tr\u00edgono con Mercurio te permite conectar con los secretos de la vida, del universo y de la energ\u00eda, la ley de atracci\u00f3n a tu <a href=\"http:\/\/www.moonmentum.com\/blog\/pronostico\/index\/conoce-y-activa-la-ley-la-atraccion\/\" target=\"_blank\">disposici\u00f3n<\/a>.<\/p>\n<p>V\u00edstete\u00a0 o conecta con tonalidades azules.<\/p>\n<p><span style=\"color: #ff6600;\"><em>S\u00edguenos<\/em><em> en twitter por <strong><a href=\"https:\/\/twitter.com\/#!\/moonmentum\" target=\"_blank\">@Moonmentum<\/a> . . .<\/strong><\/em><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Luna desde tu signo, junto a Neptuno (tu regente) y en un poderos\u00edsimo tr\u00edgono con Mercurio&#8230;<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[689],"tags":[8515,1719,585,9816,640,9291,8845,343,17205,17200,9615,1561,9869,793,1900,600],"class_list":{"0":"post-98614","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-piscis","7":"tag-12-signos-del-zodiaco","8":"tag-astrologa-lourdes-mendez","9":"tag-astrologia","10":"tag-astrologia-piscis","11":"tag-astros","12":"tag-horoscopo-diario","13":"tag-horoscopo-piscis","14":"tag-lourdes-mendez","15":"tag-piscis","16":"tag-reality-horoscope","17":"tag-signo-piscis","18":"tag-signo-zodiacal","19":"tag-signo-zodiacal-piscis","20":"tag-signos","21":"tag-signos-del-zodiaco","22":"tag-zodiaco"},"_links":{"self":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts\/98614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/comments?post=98614"}],"version-history":[{"count":0,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/posts\/98614\/revisions"}],"wp:attachment":[{"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/media?parent=98614"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/categories?post=98614"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/moonmentum.com\/blog\/wp-json\/wp\/v2\/tags?post=98614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}